{"id":96825,"date":"2023-03-04T11:26:49","date_gmt":"2023-03-04T17:26:49","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=96825"},"modified":"2023-03-04T11:26:51","modified_gmt":"2023-03-04T17:26:51","slug":"regresa-a-mexico-ayuda-humanitaria-que-apoyo-en-sofocacion-de-incendios-forestales-en-chile","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/03\/04\/regresa-a-mexico-ayuda-humanitaria-que-apoyo-en-sofocacion-de-incendios-forestales-en-chile\/","title":{"rendered":"Regresa a M\u00e9xico ayuda humanitaria que apoy\u00f3 en sofocaci\u00f3n de incendios forestales en Chile"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Los militares y brigadistas de la Comisi\u00f3n Nacional Forestal (Conafor), que participaron en tareas de sofocaci\u00f3n de incendios forestales en Chile,<strong>&nbsp;fueron recibidos con honores.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco antes de las 06:00 horas del s\u00e1bado, aterrizaron en la base militar n\u00famero 1, de Santa Luc\u00eda,<strong>&nbsp;dos aviones de la Fuerza A\u00e9rea Mexicana<\/strong>&nbsp;<strong>procedentes de Chile.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En las aeronaves<strong>&nbsp;viajaban 300 personas,<\/strong>&nbsp;entre militares y brigadistas. La comitiva parti\u00f3 de M\u00e9xico el 5 de febrero para brindar<strong>&nbsp;ayuda humanitaria<\/strong>&nbsp;en dicho pa\u00eds sudamericano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El general Brigadier Diplomado de Estado Mayor, Lauriano Carilla Rodr\u00edguez y jefe de la secci\u00f3n tercera de operaciones del Estado Mayor Conjunto de la Defensa Nacional, coment\u00f3 que &#8220;a lo largo de la historia, en diferentes latitudes se han presentado fen\u00f3menos naturales y antropog\u00e9nicos que han causado da\u00f1os severos a los seres humanos y a su entorno, como es el caso de las graves afectaciones que sufri\u00f3 recientemente el pueblo Chileno,&nbsp;<strong>provocado por m\u00e1s de 200 incendios forestales en la regi\u00f3n sur del pa\u00eds&#8221;.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Ante esta emergencia, el gobierno de M\u00e9xico en muestra de solidaridad hist\u00f3rica, de ayuda y cooperaci\u00f3n internacional, instruy\u00f3 a la Secretar\u00eda de la Defensa Nacional para que organizar\u00e1 una fuerza de ayuda humanitaria constituida por 300 mujeres y hombres experimentados del Ej\u00e9rcito y brigadistas de la Comisi\u00f3n Nacional, quienes fueron trasladados en aviones de la Fuerza A\u00e9rea Mexicana&#8221;.<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"375\" height=\"250\" src=\"https:\/\/nvnoticias.mx\/wp-content\/uploads\/2023\/03\/image.png\" alt=\"\" class=\"wp-image-96829\" srcset=\"https:\/\/nvnoticias.mx\/wp-content\/uploads\/2023\/03\/image.png 375w, https:\/\/nvnoticias.mx\/wp-content\/uploads\/2023\/03\/image-300x200.png 300w\" sizes=\"auto, (max-width: 375px) 100vw, 375px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">El evento fue encabezado por el secretario de la Defensa Nacional, Luis Crescencio Sandoval y por Beatriz de Jes\u00fas S\u00e1nchez Mu\u00f1oz, embajadora de Chile en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los soldados y brigadistas de la Conafor fueron reconocidos por su valent\u00eda, tambi\u00e9n el gobierno de Chile agradeci\u00f3 el gesto de ayuda del gobierno de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/comunidad\/llega-ayuda-humanitaria-apoyo-sofocacion-incendios-chile\" data-type=\"URL\" data-id=\"https:\/\/www.milenio.com\/politica\/comunidad\/llega-ayuda-humanitaria-apoyo-sofocacion-incendios-chile\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los militares y brigadistas de la Comisi\u00f3n Nacional Forestal (Conafor), que participaron en tareas de sofocaci\u00f3n de incendios forestales en Chile,&nbsp;fueron recibidos con honores. Poco antes de las 06:00 horas del s\u00e1bado, aterrizaron en la base militar n\u00famero 1, de Santa Luc\u00eda,&nbsp;dos aviones de la Fuerza A\u00e9rea Mexicana&nbsp;procedentes de Chile. En las aeronaves&nbsp;viajaban 300 personas,&nbsp;entre [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":5920,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[23608,5205,472,2256,292,6063,23609],"class_list":["post-96825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-apoyo-2","tag-ayuda-humanitaria","tag-chile","tag-incendios-forestales","tag-mexico","tag-regresa","tag-sofocacion","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/96825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=96825"}],"version-history":[{"count":6,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/96825\/revisions"}],"predecessor-version":[{"id":96832,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/96825\/revisions\/96832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/5920"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=96825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=96825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=96825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}