{"id":96424,"date":"2023-03-02T09:26:51","date_gmt":"2023-03-02T15:26:51","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=96424"},"modified":"2023-03-02T09:26:53","modified_gmt":"2023-03-02T15:26:53","slug":"alista-amlo-plan-contra-inflacion-entre-paises-de-america-latina","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/03\/02\/alista-amlo-plan-contra-inflacion-entre-paises-de-america-latina\/","title":{"rendered":"Alista AMLO plan contra inflaci\u00f3n entre pa\u00edses de Am\u00e9rica Latina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador anunci\u00f3 que M\u00e9xico alista un plan contra inflaci\u00f3n entre pa\u00edses de Am\u00e9rica Latina, con la finalidad de combatir las afectacionbes en la regi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la conferencia ma\u00f1anera de Palacio Nacional, el mandatario\u00a0 explic\u00f3 que se trabaja junto con\u00a0Brasil, Argentina, Colombia y Cuba, adem\u00e1s, se invitar\u00e1 a\u00a0Chile, Bolivia y Honduras, con el objetivo de tener una primera reuni\u00f3n virtual sobre este tema el pr\u00f3ximo 5 de abril.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El objetivo es invitar a distribuidores, productores y comerciantes que venden alimentos para que haya mejores precios en el mercado interno de los pa\u00edses.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Aprovecho para comentarles que, debido a esto, vamos a llevar a cabo un plan antiinflacionario de ayuda mutua para el crecimiento, para el intercambio econ\u00f3mico comercial con pa\u00edses de Am\u00e9rica Latina&#8221;, dijo L\u00f3pez Obrador.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><br>&#8220;Ayer, con este prop\u00f3sito habl\u00e9 con el presidente Lula, tambi\u00e9n con el presidente Petro, Miguel D\u00edaz Canel de Cuba, con el presidente de Argentina, Alberto Fern\u00e1ndez. Nos faltan llamadas aunque Alberto Fern\u00e1ndez se comprometi\u00f3 a hacerlo con el presidente de Chile y con el de Bolivia, Gabriel Boric y Luis Arce, yo voy a hablar hoy con la se\u00f1ora Xiomara Castro de Honduras&#8221;, expres\u00f3.<br><\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Por ahora, quedaron fuera de la convocatoria Per\u00fa y Ecuador, sin embargo, no se descarta que se sigan sumando pa\u00edses a este plan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de la reuni\u00f3n virtual, los pa\u00edses que se sumen a esta iniciativa tendr\u00e1n un encuentro presencial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan el Presidente, a partir de estas primeras llamadas se instruy\u00f3 a que los cancilleres y secretarios de hacienda y econom\u00eda de los pa\u00edses empiecen a trabajar para buscar intercambios en exportaci\u00f3n, importaci\u00f3n de alimentos y de otros bienes con el fin de enfrentar la carest\u00eda de manera conjunta en la regi\u00f3n.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/amlo-alista-plan-contra-inflacion-paises-america-latina\" data-type=\"URL\" data-id=\"https:\/\/www.milenio.com\/politica\/amlo-alista-plan-contra-inflacion-paises-america-latina\">Milenio<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador anunci\u00f3 que M\u00e9xico alista un plan contra inflaci\u00f3n entre pa\u00edses de Am\u00e9rica Latina, con la finalidad de combatir las afectacionbes en la regi\u00f3n. En la conferencia ma\u00f1anera de Palacio Nacional, el mandatario\u00a0 explic\u00f3 que se trabaja junto con\u00a0Brasil, Argentina, Colombia y Cuba, adem\u00e1s, se invitar\u00e1 a\u00a0Chile, Bolivia y Honduras, [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":93910,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[11526,2905,188,5459,2978,7431,162],"class_list":["post-96424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-alista","tag-america-latina","tag-amlo","tag-contra","tag-inflacion","tag-paises","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/96424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=96424"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/96424\/revisions"}],"predecessor-version":[{"id":96427,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/96424\/revisions\/96427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/93910"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=96424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=96424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=96424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}