{"id":94728,"date":"2023-02-18T13:08:40","date_gmt":"2023-02-18T19:08:40","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=94728"},"modified":"2023-02-18T13:08:41","modified_gmt":"2023-02-18T19:08:41","slug":"el-patron-habria-sido-el-autor-intelectual-del-intento-de-homicidio-a-ciro-gomez","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/02\/18\/el-patron-habria-sido-el-autor-intelectual-del-intento-de-homicidio-a-ciro-gomez\/","title":{"rendered":"&#8220;El Patr\u00f3n&#8221; habr\u00eda sido el autor intelectual del intento de homicidio a Ciro G\u00f3mez"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tras el intento de homicidio del periodista&nbsp;Ciro G\u00f3mez Leyva, las autoridades han informado sobre la&nbsp;<strong>vinculaci\u00f3n&nbsp;a proceso a 11 de los 12 detenidos<\/strong>. El supuesto&nbsp;tirador, apodado como &#8220;<strong>El Bart<\/strong>&#8220;, no compareci\u00f3, por lo que se llevar\u00e1 a cabo el 18 de febrero, afirm\u00f3 la&nbsp;<strong>Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico<\/strong>&nbsp;(FGJCDMX).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El \u00f3rgano capitalino&nbsp;confirm\u00f3 que se cuentan con aproximadamente 25 datos de prueba basados en entrevistas, cateos, intervenciones de llamadas telef\u00f3nicas, entre otras indagatorias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El ataque contra este integrante habr\u00eda sido por haber &#8220;transmitido informaci\u00f3n indebida&#8221;. En este sentido, se encontr\u00f3 relaci\u00f3n con esta ejecuci\u00f3n y las operaciones del&nbsp;<strong>C\u00e1rtel Jalisco Nueva Generaci\u00f3n<\/strong>&nbsp;(CJNG), puesto que &#8220;El Patr\u00f3n&#8221; frecuentaba la contrataci\u00f3n de sicarios para dicha organizaci\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Somos leales al C\u00e1rtel Jalisco Nueva Generaci\u00f3n, no diremos nada y nadie se va a ponchar&#8221;, aseguraron los imputados, confirmando su vinculaci\u00f3n con el grupo delictivo.&nbsp;<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente:<a href=\"https:\/\/heraldodemexico.com.mx\/nacional\/2023\/2\/18\/caso-ciro-gomez-leyva-el-patron-vinculado-al-cjng-habria-sido-el-autor-intelectual-del-intento-de-homicidio-482596.html\" data-type=\"URL\" data-id=\"https:\/\/heraldodemexico.com.mx\/nacional\/2023\/2\/18\/caso-ciro-gomez-leyva-el-patron-vinculado-al-cjng-habria-sido-el-autor-intelectual-del-intento-de-homicidio-482596.html\"> El Heraldo de M\u00e9xico <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el intento de homicidio del periodista&nbsp;Ciro G\u00f3mez Leyva, las autoridades han informado sobre la&nbsp;vinculaci\u00f3n&nbsp;a proceso a 11 de los 12 detenidos. El supuesto&nbsp;tirador, apodado como &#8220;El Bart&#8220;, no compareci\u00f3, por lo que se llevar\u00e1 a cabo el 18 de febrero, afirm\u00f3 la&nbsp;Fiscal\u00eda General de Justicia de la Ciudad de M\u00e9xico&nbsp;(FGJCDMX).&nbsp; El \u00f3rgano capitalino&nbsp;confirm\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":86757,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[18027,7612,21865,4564,23309],"class_list":["post-94728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-alberto-el-patron","tag-autor","tag-ciro-gomez-leyva","tag-homicidio","tag-intelectual","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/94728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=94728"}],"version-history":[{"count":4,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/94728\/revisions"}],"predecessor-version":[{"id":94732,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/94728\/revisions\/94732"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/86757"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=94728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=94728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=94728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}