{"id":92757,"date":"2023-02-02T12:57:42","date_gmt":"2023-02-02T18:57:42","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=92757"},"modified":"2023-02-02T12:57:42","modified_gmt":"2023-02-02T18:57:42","slug":"sabia-dea-de-contactos-de-garcia-luna-con-el-crimen-organizado-desde-2010","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/02\/02\/sabia-dea-de-contactos-de-garcia-luna-con-el-crimen-organizado-desde-2010\/","title":{"rendered":"Sab\u00eda DEA de contactos de Garc\u00eda Luna con el cr\u00edmen organizado desde 2010"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Miguel Madrigal<\/strong>, agente de la Agencia Antinarc\u00f3ticos (<strong>DEA<\/strong>) de\u00a0<strong>Estados Unidos<\/strong>, afirm\u00f3 este jueves en el juicio contra\u00a0<strong>Genaro Garc\u00eda Luna\u00a0<\/strong>que la DEA sab\u00eda de los contactos del exsecretario mexicano de Seguridad con el\u00a0<strong>c\u00e1rtel de Sinaloa\u00a0<\/strong>desde 2010.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Madrigal afirm\u00f3 que se reuni\u00f3 con\u00a0<strong>Sergio Villarreal Barrag\u00e1n<\/strong>, alias \u201c<strong>El Grande<\/strong>\u201d y quien testific\u00f3 la semana pasada, horas despu\u00e9s de que fue detenido, en 2010, en M\u00e9xico. \u201cEl Grande\u201d, lugarteniente del c\u00e1rtel de los Beltr\u00e1n Leyva, fue extraditado a Estados Unidos en 2012.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su reuni\u00f3n, continu\u00f3 Madrigal, Villarreal le habl\u00f3 de los \u201cnegocios de Genaro&nbsp;<strong>Garc\u00eda Luna<\/strong>&nbsp;con el c\u00e1rtel cuando era polic\u00eda estatal\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n dijo haber visto un video en el que identific\u00f3 la\u00a0<strong>Jeep Cherokee<\/strong>\u00a0que pertenec\u00eda al entonces comandante de la Polic\u00eda Federal, \u00c9dgar Vallardo. El veh\u00edculo se estacion\u00f3 frente a la casa de<strong>\u00a0Jes\u00fas \u201cEl Rey\u201d Zambada<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.eluniversal.com.mx\/mundo\/garcia-luna-dea-sabia-de-contactos-del-exfuncionario-con-el-cartel-de-sinaloa-desde-2010\" data-type=\"URL\" data-id=\"https:\/\/www.eluniversal.com.mx\/mundo\/garcia-luna-dea-sabia-de-contactos-del-exfuncionario-con-el-cartel-de-sinaloa-desde-2010\">El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Miguel Madrigal, agente de la Agencia Antinarc\u00f3ticos (DEA) de\u00a0Estados Unidos, afirm\u00f3 este jueves en el juicio contra\u00a0Genaro Garc\u00eda Luna\u00a0que la DEA sab\u00eda de los contactos del exsecretario mexicano de Seguridad con el\u00a0c\u00e1rtel de Sinaloa\u00a0desde 2010. Madrigal afirm\u00f3 que se reuni\u00f3 con\u00a0Sergio Villarreal Barrag\u00e1n, alias \u201cEl Grande\u201d y quien testific\u00f3 la semana pasada, horas despu\u00e9s de [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":90923,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[22930,22931,478,4504],"class_list":["post-92757","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-contactos","tag-crimen-organizado-2","tag-dea","tag-genaro-garcia-luna","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92757","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=92757"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92757\/revisions"}],"predecessor-version":[{"id":92758,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92757\/revisions\/92758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/90923"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=92757"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=92757"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=92757"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}