{"id":92565,"date":"2023-02-01T11:09:28","date_gmt":"2023-02-01T17:09:28","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=92565"},"modified":"2023-02-01T11:09:29","modified_gmt":"2023-02-01T17:09:29","slug":"no-hay-duda-el-aicm-era-usado-para-pasar-drogas-en-tiempos-de-garcia-luna-amlo","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/02\/01\/no-hay-duda-el-aicm-era-usado-para-pasar-drogas-en-tiempos-de-garcia-luna-amlo\/","title":{"rendered":"&#8220;No hay duda&#8221; el AICM era usado para pasar drogas en tiempos de Garc\u00eda Luna: AMLO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador dijo que &#8220;no hay duda&#8221; que cuando\u00a0<strong>Genaro Garc\u00eda Luna<\/strong>\u00a0era secretario de Seguridad P\u00fablica Federal el Aeropuerto Internacional de la Ciudad de M\u00e9xico (<strong>AICM<\/strong>) era\u00a0utilizado para pasar droga.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Ya muchos saben de que c\u00f3mo met\u00edan droga por el aeropuerto. Una vez hasta hubo una balacera ah\u00ed en el aeropuerto.&nbsp;Ahora con el juicio de Garc\u00eda Luna (&#8230;) dice el enviado que hab\u00eda un operativo para dejar sin vigilancia el aeropuerto cuando se les ordenaba, para que pasaran la droga&#8221;.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Cuestion\u00f3 a la organizaci\u00f3n internacional, &#8220;que b\u00e1sicamente funciona en Estados Unidos&#8221;, encargada de calificar la calidad y seguridad de los aeropuertos, pues acus\u00f3 que &#8220;<strong>hay mucha simulaci\u00f3n<\/strong>&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presidente se\u00f1al\u00f3 que cuando&nbsp;<strong>a pesar del trasiego de droga<\/strong>&nbsp;y la presunta participaci\u00f3n de narcotraficantes, el AICM ten\u00eda la categor\u00eda 1. &#8220;Esto lo digo como para que no estemos creyendo que son infalibles estas organizaciones&#8221;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Ten\u00eda una clave 35-40, 35-45, y el Aeropuerto de la Ciudad de M\u00e9xico se quedaba sin vigilancia para pasar droga, manejado por la Polic\u00eda Federal que tanto defienden los conservadores, que no apoyaron a la Guardia Nacional&#8221;.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Es interesante todo lo que est\u00e1 sucediendo, independientemente de lo que vaya a concluirse, eso del aeropuerto&nbsp;<strong>no hay duda de que lo manejaban<\/strong>&#8220;.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ayer, Ra\u00fal Arellano Aguilera, ex agente de la extinta Polic\u00eda Federal, describi\u00f3 la forma en que comandantes de esa dependencia asignados en el AICM operaban para presuntamente\u00a0<strong>dejar pasar cargamentos<\/strong>\u00a0\u201ccon\u00a0droga, dinero y armas\u201d durante 2007.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La declaraci\u00f3n del ex agente fue conocida en la audiencia en la\u00a0Corte Federal del Distrito Este de Nueva York, donde testigos como los narcotraficantes Sergio Villarreal Barrag\u00e1n,\u00a0<em>El Grande<\/em>; Tirso Mart\u00ednez,\u00a0<em>El Futbolista<\/em>, y \u00d3scar Nava Valencia,\u00a0<em>El Lobo<\/em>, han testificado en el\u00a0juicio contra Genaro Garc\u00eda Luna, ex secretario de Seguridad P\u00fablica acusado de presuntos nexos con el crimen organizado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/aicm-paso-droga-tiempos-garcia-luna-amlo-no-hay-duda\" data-type=\"URL\" data-id=\"https:\/\/www.milenio.com\/politica\/aicm-paso-droga-tiempos-garcia-luna-amlo-no-hay-duda\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador dijo que &#8220;no hay duda&#8221; que cuando\u00a0Genaro Garc\u00eda Luna\u00a0era secretario de Seguridad P\u00fablica Federal el Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM) era\u00a0utilizado para pasar droga. &#8220;Ya muchos saben de que c\u00f3mo met\u00edan droga por el aeropuerto. Una vez hasta hubo una balacera ah\u00ed en el aeropuerto.&nbsp;Ahora con [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":80608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[6573,188,1201,4504],"class_list":["post-92565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-aicm","tag-amlo","tag-drogas","tag-genaro-garcia-luna","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=92565"}],"version-history":[{"count":4,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92565\/revisions"}],"predecessor-version":[{"id":92569,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92565\/revisions\/92569"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/80608"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=92565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=92565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=92565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}