{"id":92290,"date":"2023-01-30T15:28:28","date_gmt":"2023-01-30T21:28:28","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=92290"},"modified":"2023-01-30T15:28:30","modified_gmt":"2023-01-30T21:28:30","slug":"electrificara-la-cfe-960-kilometros-del-tren-maya","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/01\/30\/electrificara-la-cfe-960-kilometros-del-tren-maya\/","title":{"rendered":"Electrificar\u00e1 la CFE 960 kil\u00f3metros del Tren Maya"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n Federal de Electricidad (CFE) lleva a cabo una serie de obras de infraestructura el\u00e9ctrica que dotar\u00e1n de energ\u00eda al tramo electrificado del Tren Maya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el director general de la empresa productiva del Estado, Manuel Bartlett D\u00edaz, lo que se est\u00e1 haciendo equivale a instalar nuevamente un sistema el\u00e9ctrico como el de la ciudad de M\u00e9rida.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que para la operaci\u00f3n del Tren Maya en el tramo electrificado que comprende 690 kil\u00f3metros, la CFE realiza 53 obras de infraestructura el\u00e9ctrica, con una inversi\u00f3n de 6,587 millones de pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dichas obras implican la construcci\u00f3n de 7 subestaciones el\u00e9ctricas tractoras que conectar\u00e1n al tren con la red el\u00e9ctrica, regular\u00e1n la tensi\u00f3n de la energ\u00eda y le proporcionar\u00e1n fuerza de tracci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De estas subestaciones, 3 se ubicar\u00e1n entre las ciudades de M\u00e9rida y Canc\u00fan y cuatro se localizar\u00e1n entre Canc\u00fan y Chetumal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las obras de infraestructura el\u00e9ctrica que hace la CFE generan 2,100 empleos directos y 1,422 indirectos; participan 10 empresas contratistas, 24 subcontratistas y 70 proveedores, e implican el uso de m\u00e1s de 350 unidades de maquinaria y equipos, as\u00ed como m\u00e1s de 720 mil toneladas de materiales principales, como acero de refuerzo, concreto y material de banco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De estas subestaciones, 3 se ubicar\u00e1n entre las ciudades de M\u00e9rida y Canc\u00fan y cuatro se localizar\u00e1n entre Canc\u00fan y Chetumal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las obras de infraestructura el\u00e9ctrica que hace la CFE generan 2,100 empleos directos y 1,422 indirectos; participan 10 empresas contratistas, 24 subcontratistas y 70 proveedores, e implican el uso de m\u00e1s de 350 unidades de maquinaria y equipos, as\u00ed como m\u00e1s de 720 mil toneladas de materiales principales, como acero de refuerzo, concreto y material de banco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para este obra insignia de la administraci\u00f3n del presidente Andr\u00e9s Manuel L\u00f3pez Obrados, la CFE tambi\u00e9n est\u00e1 construyendo 556 kil\u00f3metros de l\u00edneas de media tensi\u00f3n para brindar el suministro el\u00e9ctrico a 170 servicios que se requieren para la operaci\u00f3n del Tren Maya.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior consiste en 119 casetas t\u00e9cnicas, 34 estaciones y paraderos, 6 talleres y cocheras, 8 bases de mantenimiento y 3 edificaciones de la Secretar\u00eda de la Defensa Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Estas obras se realizan con una inversi\u00f3n de 1,587 millones de pesos y generar\u00e1n un total 2,000 empleos directos y 6,700 indirectos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n como parte de la infraestructura el\u00e9ctrica para el Tren Maya, la CFE est\u00e1 desarrollando la Central Fotovoltaica Nachi Cocom, en M\u00e9rida, la cual aprovechar\u00e1 infraestructura existente de la empresa, tendr\u00e1 una capacidad de generaci\u00f3n de 7.5 megawatts e implica una inversi\u00f3n de 193 millones de pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente:<a href=\"https:\/\/www.forbes.com.mx\/asi-electrificara-la-cfe-960-kilometros-del-tren-maya\/\" data-type=\"URL\" data-id=\"https:\/\/www.forbes.com.mx\/asi-electrificara-la-cfe-960-kilometros-del-tren-maya\/\"> Forbes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Federal de Electricidad (CFE) lleva a cabo una serie de obras de infraestructura el\u00e9ctrica que dotar\u00e1n de energ\u00eda al tramo electrificado del Tren Maya. De acuerdo con el director general de la empresa productiva del Estado, Manuel Bartlett D\u00edaz, lo que se est\u00e1 haciendo equivale a instalar nuevamente un sistema el\u00e9ctrico como el [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":50721,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[821,22869,12648,4217],"class_list":["post-92290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-cfe","tag-electrificara","tag-kilometros","tag-tren-maya","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=92290"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92290\/revisions"}],"predecessor-version":[{"id":92296,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/92290\/revisions\/92296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/50721"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=92290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=92290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=92290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}