{"id":91683,"date":"2023-01-25T14:22:36","date_gmt":"2023-01-25T20:22:36","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=91683"},"modified":"2023-01-25T14:22:37","modified_gmt":"2023-01-25T20:22:37","slug":"cofepris-llama-a-denunciar-venta-ilegal-de-clonazepam","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/01\/25\/cofepris-llama-a-denunciar-venta-ilegal-de-clonazepam\/","title":{"rendered":"Cofepris llama a denunciar venta ilegal de Clonazepam"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n Federal para la Protecci\u00f3n contra Riesgos Sanitarios (Cofepris) llam\u00f3 a la ciudadan\u00eda a denunciar la venta ilegal de\u00a0Clonazepam sin receta, ya que este medicamento es utilizado por ni\u00f1as, ni\u00f1os y adolescentes para realizar\u00a0retos virales\u00a0y ser subidos a redes sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n indic\u00f3 que el mal uso de este medicamento podr\u00eda poner en riesgo la integridad f\u00edsica. \u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que el Clonazepam tiene\u00a0efectos secundarios\u00a0que van desde la somnolencia, mareos y n\u00e1useas hasta p\u00e9rdida de equilibrio, problemas de coordinaci\u00f3n, dificultad para pensar o recordar, dolor de cabeza, muscular o de articulaciones; visi\u00f3n borrosa, temblores, incontinencia o retenci\u00f3n urinaria e incremento de saliva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n puede provocar problemas graves de respiraci\u00f3n o\u00a0sedaci\u00f3n; incluso, si se combina dicho ansiol\u00edtico con determinados medicamentos, puede producir coma.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Contraindicaciones del Clonazepam&nbsp;<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">El Clonazepam est\u00e1 contraindicado para personas con hipersensibilidad a las benzodiacepinas; insuficiencia hep\u00e1tica; insuficiencia renal; problemas respiratorios; y afecci\u00f3n ocular que da\u00f1a el nervio \u00f3ptico, mejor conocido como glaucoma, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La\u00a0Cofepris\u00a0puso a disposici\u00f3n el n\u00famero telef\u00f3nico para denuncias sanitarias 800 033 5050; o de forma presencial, en los Centros Integrales de Servicio, ubicados en cada entidad federativa; y en la secci\u00f3n de Denuncia Sanitaria en la p\u00e1gina institucional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, hizo un llamado a los padres de familia para que orienten a los menores de edad sobre los\u00a0riesgos\u00a0que conlleva el consumo de\u00a0medicamentos controlados, y la participaci\u00f3n en retos virales que atenten contra su integridad f\u00edsica.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201c<em>Cofepris exhorta a padres y madres de familia, tutores, personas cuidadoras y docentes a orientar sobre los graves riesgos a la salud por el uso y consumo de sustancias controladas. Igualmente, invita a ni\u00f1as, ni\u00f1os y adolescentes a evitar difundir y participar en retos que pongan en riesgo su vida<\/em>\u201d, determin\u00f3.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/cofepris-llama-denunciar-venta-ilegal-de-clonazepam-utilizado-en-retos-virales\">El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n Federal para la Protecci\u00f3n contra Riesgos Sanitarios (Cofepris) llam\u00f3 a la ciudadan\u00eda a denunciar la venta ilegal de\u00a0Clonazepam sin receta, ya que este medicamento es utilizado por ni\u00f1as, ni\u00f1os y adolescentes para realizar\u00a0retos virales\u00a0y ser subidos a redes sociales. La Comisi\u00f3n indic\u00f3 que el mal uso de este medicamento podr\u00eda poner en riesgo [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":91684,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[20930,649],"class_list":["post-91683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-clonazepam","tag-cofepris","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/91683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=91683"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/91683\/revisions"}],"predecessor-version":[{"id":91685,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/91683\/revisions\/91685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/91684"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=91683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=91683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=91683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}