{"id":91158,"date":"2023-01-21T19:47:00","date_gmt":"2023-01-22T01:47:00","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=91158"},"modified":"2023-01-21T21:49:57","modified_gmt":"2023-01-22T03:49:57","slug":"abre-la-administracion-federal-de-aviacion-de-eu-oficinas-en-mexico-anuncio-ken-salazar","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/01\/21\/abre-la-administracion-federal-de-aviacion-de-eu-oficinas-en-mexico-anuncio-ken-salazar\/","title":{"rendered":"Abre la Administraci\u00f3n Federal de Aviaci\u00f3n de EU oficinas en M\u00e9xico, anunci\u00f3 Ken Salazar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ken Salazar\u00a0anunci\u00f3 que la\u00a0Administraci\u00f3n Federal de Aviaci\u00f3n de los Estados Unidos\u00a0(FAA) abri\u00f3 la primera oficina en M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su mensaje apunt\u00f3 que se encuentran trabajando en &#8220;afianzar los lazos de nuestros pa\u00edses&#8221;, y que esta acci\u00f3n fortalecer\u00e1 la cooperaci\u00f3n de las autoridades y el sector privado de la industria de la aviaci\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Para los Estados Unidos no hay un socio m\u00e1s importante en aviaci\u00f3n civil que M\u00e9xico&#8221; dijo el representante de Estados Unidos. Salazar destac\u00f3 que M\u00e9xico es el pa\u00eds con m\u00e1s vuelos hacia Estados Unidos.<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"es\" dir=\"ltr\">???????? no tiene socio m\u00e1s importante en aviaci\u00f3n civil que ????????. Me complace anunciar que <a href=\"https:\/\/twitter.com\/FAANews?ref_src=twsrc%5Etfw\">@FAANEWS<\/a> abri\u00f3 su primera oficina en ???????? para mejorar cooperaci\u00f3n con autoridades de aviaci\u00f3n e iniciativa privada mientras se fortalecemos integraci\u00f3n en Am\u00e9rica del Norte. <a href=\"https:\/\/t.co\/3YNwo409kR\">https:\/\/t.co\/3YNwo409kR<\/a><\/p>&mdash; Embajador Ken Salazar (@USAmbMex) <a href=\"https:\/\/twitter.com\/USAmbMex\/status\/1616493107159105639?ref_src=twsrc%5Etfw\">January 20, 2023<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Uno de cada cuatro estadounidenses que viajaron al extranjero, lo hicieron hacia alg\u00fan destino mexicano, representando alrededor de 13 millones de viajeros&#8221; se\u00f1al\u00f3 Ken Salazar.\u00a0<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En la reuni\u00f3n estuvo acompa\u00f1ado con l\u00edderes de Aeromexico, Viva Aerobus, Volaris, entre otros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/administracion-federal-de-aviacion-de-eu-abre-oficina-en-mexico-anuncia-ken-salazar\">El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ken Salazar\u00a0anunci\u00f3 que la\u00a0Administraci\u00f3n Federal de Aviaci\u00f3n de los Estados Unidos\u00a0(FAA) abri\u00f3 la primera oficina en M\u00e9xico. En su mensaje apunt\u00f3 que se encuentran trabajando en &#8220;afianzar los lazos de nuestros pa\u00edses&#8221;, y que esta acci\u00f3n fortalecer\u00e1 la cooperaci\u00f3n de las autoridades y el sector privado de la industria de la aviaci\u00f3n. &#8220;Para los Estados [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":91159,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[22713,183,5523,292,2314],"class_list":["post-91158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-administracion-federal-de-aviacion-de-estados-unidos","tag-estados-unidos","tag-ken-salazar","tag-mexico","tag-oficinas","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/91158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=91158"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/91158\/revisions"}],"predecessor-version":[{"id":91160,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/91158\/revisions\/91160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/91159"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=91158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=91158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=91158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}