{"id":90152,"date":"2023-01-13T13:43:42","date_gmt":"2023-01-13T19:43:42","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=90152"},"modified":"2023-01-13T13:43:43","modified_gmt":"2023-01-13T19:43:43","slug":"juez-niega-amparo-contra-extradicion-a-ovidio-guzman","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/01\/13\/juez-niega-amparo-contra-extradicion-a-ovidio-guzman\/","title":{"rendered":"Juez niega amparo contra extradici\u00f3n a Ovidio Guzm\u00e1n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Un juez de distrito de Amparo neg\u00f3 la protecci\u00f3n de la justicia federal a Ovidio Guzm\u00e1n L\u00f3pez, alias &#8216;El Rat\u00f3n&#8217;, debido a&nbsp;que carece de competencia legal para resolver y conocer del caso por temas territoriales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El juez de distrito le neg\u00f3 la suspensi\u00f3n definitiva en los juicios de amparo, promovido por la defensa de dicho sujeto en contra de su detenci\u00f3n con fines de extradici\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El hijo de Joaqu\u00edn &#8216;El Chapo&#8217; Guzm\u00e1n Loera se encuentra a disposici\u00f3n de un juez de control del Centro de Justicia Penal Federal del Estado de M\u00e9xico de Almoloya de Ju\u00e1rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 5 de enero pasado, Ovidio Guzm\u00e1n obtuvo de un juez una suspensi\u00f3n de oficio por supuestos maltratos f\u00edsicos y psicol\u00f3gicos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Rat\u00f3n asegur\u00f3 que le han impedido mantener comunicaci\u00f3n con su familia. Los abogados de Ovidio pueden impugnar dicha resoluci\u00f3n en las pr\u00f3ximas horas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/ovidio-guzman-juez-niega-amparo-extradicion\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un juez de distrito de Amparo neg\u00f3 la protecci\u00f3n de la justicia federal a Ovidio Guzm\u00e1n L\u00f3pez, alias &#8216;El Rat\u00f3n&#8217;, debido a&nbsp;que carece de competencia legal para resolver y conocer del caso por temas territoriales. El juez de distrito le neg\u00f3 la suspensi\u00f3n definitiva en los juicios de amparo, promovido por la defensa de dicho [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":89144,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[1547,1005,7928,162],"class_list":["post-90152","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-amparo","tag-extradicion","tag-ovidio-guzman","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/90152","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=90152"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/90152\/revisions"}],"predecessor-version":[{"id":90153,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/90152\/revisions\/90153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/89144"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=90152"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=90152"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=90152"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}