{"id":8972,"date":"2021-03-25T18:21:02","date_gmt":"2021-03-26T00:21:02","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=8972"},"modified":"2021-03-25T18:21:03","modified_gmt":"2021-03-26T00:21:03","slug":"agradecen-adultos-mayores-vacunacion-en-coatzacoalcos","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/03\/25\/agradecen-adultos-mayores-vacunacion-en-coatzacoalcos\/","title":{"rendered":"Agradecen adultos mayores vacunaci\u00f3n en Coatzacoalcos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Julio Escobar \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coatzacoalcos.- Luego del anuncio de la jornada de vacunaci\u00f3n anti covid-19 en Coatzacoalcos que arrancar\u00e1 este 29 de marzo, adultos mayores celebraron y agradecieron la tan esperada fecha.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En entrevista, detallaron que es importante aplicarse la vacuna para fortalecer las defensas y evitar contagios; por lo que no dudan en aplic\u00e1rsela.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cPara no est\u00e1 bien porque es una manera de protegernos, yo si conf\u00edo en la dosis, no nos mata, nos protege como toda vacuna pero sino no las aplicamos estamos en m\u00e1s riesgo\u201d, Amelia Alcudia Alvarado, ciudadana.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Al cuestionarle si preferir\u00edan otra vacuna que la Sinovac que es la que llegar\u00e1 a este municipio, dijeron que no, que cualquier dosis es buena para la prevenci\u00f3n del virus.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cSi es bueno aplicarse la vacuna para tener m\u00e1s protecci\u00f3n y confiar en la vacuna, los de salud nos mandan a vacunar, hay que seguirse cuidando, usar el cubre boca y mantener la distancia\u201d, coment\u00f3.\u00a0<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n, muchos est\u00e1n conscientes de que la vacuna los proteger\u00e1 pero no garantiza inmunidad por lo que es importante seguir cuid\u00e1ndose y continuar con las medidas de salud.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Julio Escobar \/ NV Noticias Coatzacoalcos.- Luego del anuncio de la jornada de vacunaci\u00f3n anti covid-19 en Coatzacoalcos que arrancar\u00e1 este 29 de marzo, adultos mayores celebraron y agradecieron la tan esperada fecha.\u00a0 En entrevista, detallaron que es importante aplicarse la vacuna para fortalecer las defensas y evitar contagios; por lo que no dudan en [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":8973,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[156],"tags":[1842,504,175,809],"class_list":["post-8972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-anticovid","tag-coatzacoalcos","tag-covid-19","tag-vacunacion","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/8972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=8972"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/8972\/revisions"}],"predecessor-version":[{"id":8974,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/8972\/revisions\/8974"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/8973"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=8972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=8972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=8972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}