{"id":89437,"date":"2023-01-09T10:16:01","date_gmt":"2023-01-09T16:16:01","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=89437"},"modified":"2023-01-09T10:16:03","modified_gmt":"2023-01-09T16:16:03","slug":"visita-jill-biden-a-la-basilica-de-guadalupe","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/01\/09\/visita-jill-biden-a-la-basilica-de-guadalupe\/","title":{"rendered":"Visita Jill Biden a la Bas\u00edlica de Guadalupe"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Despu\u00e9s de aterrizar en el Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM), la<strong>&nbsp;primera dama de Estados Unidos, Jill Biden,&nbsp;<\/strong>fue recibida por la escritora&nbsp;<strong>Beatriz Guti\u00e9rrez M\u00fcller<\/strong>, esposa del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, con quien&nbsp;<strong>visit\u00f3 la Bas\u00edlica de Guadalupe.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue cerca de las 16:50 horas que la primera dama estadounidense&nbsp;aterriz\u00f3 en la Base A\u00e9rea Militar No.19, en el AICM&nbsp;para cumplir con una agenda paralela a la de Joe Biden en M\u00e9xico. Al igual que el mandatario, ella tambi\u00e9n ser\u00e1 resguardada por un robusto dispositivo de seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El compa\u00f1\u00eda de la esposa de Ken Salazar, embajador de Estados Unidos en M\u00e9xico,&nbsp;<strong>Esperanza Salazar<\/strong>&nbsp;y&nbsp;<strong>Stephanie Syptak Ramnath<\/strong>, jefa adjunta de Misi\u00f3n de la Embajada de Estados Unidos, las esposas de los mandatarios fueron a un recorrido en el recinto ubicado en la alcald\u00eda Gustavo A. Madero.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cComenc\u00e9 mi viaje a la Ciudad de M\u00e9xico con una visita a la hermosa Bas\u00edlica de Nuestra Se\u00f1ora de Guadalupe\u201d, dijo la primera dama de EEUU.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Las visitantes fueron recibidas por el rector de la Bas\u00edlica de Guadalupe,&nbsp;<strong>Monse\u00f1or Salvador Mart\u00ednez&nbsp;<\/strong>\u00c1vila, quien tambi\u00e9n les ofreci\u00f3 un breve recorrido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el sitio, las hom\u00f3logas firmaron un libro de registro. Asimismo,&nbsp;<strong>Jill Biden ofreci\u00f3 una veladora y un arreglo floral&nbsp;<\/strong>en un<strong>&nbsp;altar de la Virgen de Guadalupe&nbsp;<\/strong>colocado al exterior al recinto mariano.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cerca de las 18:00 horas se retiraron de la Bas\u00edlica para irse a descansar, pues el lunes 9 de enero tendr\u00e1n una agenda que cumplir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe recordar que Joe y Jill Biden son la<strong>&nbsp;segunda pareja en la Casa Blanca con religi\u00f3n cat\u00f3lica&nbsp;<\/strong>desde John F. Kennedy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Joe Biden hab\u00eda visitado la Bas\u00edlica de Guadalupe en el 2012 cuando era vicepresidente de Barack Obama. En 2021 record\u00f3 esa visita en una reuni\u00f3n virtual que tuvo con L\u00f3pez Obrador; dijo que su hijo Beau Biden, quien falleci\u00f3 a los 46 a\u00f1os en 2015 por un tumor cerebral,&nbsp;<strong>ten\u00eda un rosario de la Virgen de Guadalupe<\/strong>, considerada como una \u201cmadre\u201d para millones de mexicanos, y que desde entonces conserva el objeto.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cMis visitas me permitieron conocer M\u00e9xico y su gente, y a la Virgen de Guadalupe; todav\u00eda tengo el rosario que ten\u00eda mi hijo cuando falleci\u00f3\u201d, dijo Joe Biden, quien adem\u00e1s mostr\u00f3 el rosario que ten\u00eda en la mu\u00f1eca izquierda.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">A las 11:30 horas del lunes 9 de enero, Jill Biden ofrecer\u00e1 un di\u00e1logo referente al empoderamiento de las mujeres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Posteriormente, a las 12:45 horas acudir\u00e1 a un partido estudiantil de Tochito NFL en una escuela capitalina. A las 17:00 horas se reunir\u00e1 nuevamente con la acad\u00e9mica Guti\u00e9rrez M\u00fcller para presidir el evento<em>&nbsp;Fandango por la Lectura&nbsp;<\/em>en Palacio Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El martes 10 de enero, en punto de las 12:15, Jill Biden, Guti\u00e9rrez M\u00fcller y&nbsp;<strong>Sophie Gr\u00e9goire Trudeau,&nbsp;<\/strong>esposa del primer ministro de Canad\u00e1, Justin Trudeau, tendr\u00e1n un almuerzo privado. A las 13:30 horas las tres primeras damas har\u00e1n un recorrido por el&nbsp;<strong>Templo Mayor&nbsp;<\/strong>en el Centro Hist\u00f3rico, siendo la \u00faltima actividad conjunta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Paralelamente, los presidentes Joe Biden, Andr\u00e9s Manuel L\u00f3pez Obrador y el primer ministro Justin Trudeau se reunir\u00e1n para llevar a cabo la\u00a0<strong>X Cumbre de L\u00edderes de Am\u00e9rica del Norte<\/strong>, donde hablar\u00e1n sobre migraci\u00f3n, econom\u00eda y medio ambiente, entre otros temas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/america\/mexico\/2023\/01\/09\/asi-fue-la-visita-de-jill-biden-a-la-basilica-de-guadalupe\/\" data-type=\"URL\" data-id=\"https:\/\/www.infobae.com\/america\/mexico\/2023\/01\/09\/asi-fue-la-visita-de-jill-biden-a-la-basilica-de-guadalupe\/\">Infobae<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu\u00e9s de aterrizar en el Aeropuerto Internacional de la Ciudad de M\u00e9xico (AICM), la&nbsp;primera dama de Estados Unidos, Jill Biden,&nbsp;fue recibida por la escritora&nbsp;Beatriz Guti\u00e9rrez M\u00fcller, esposa del presidente Andr\u00e9s Manuel L\u00f3pez Obrador, con quien&nbsp;visit\u00f3 la Bas\u00edlica de Guadalupe. Fue cerca de las 16:50 horas que la primera dama estadounidense&nbsp;aterriz\u00f3 en la Base A\u00e9rea Militar [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":89447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[21773,10258,162,8868],"class_list":["post-89437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-basilica-de-guadalupe","tag-jill-biden","tag-portada","tag-visita","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=89437"}],"version-history":[{"count":9,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89437\/revisions"}],"predecessor-version":[{"id":89446,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89437\/revisions\/89446"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/89447"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=89437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=89437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=89437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}