{"id":89412,"date":"2023-01-09T09:23:40","date_gmt":"2023-01-09T15:23:40","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=89412"},"modified":"2023-01-09T09:23:41","modified_gmt":"2023-01-09T15:23:41","slug":"refrenda-amlo-apoyo-a-lula-da-silva-tras-protestas","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/01\/09\/refrenda-amlo-apoyo-a-lula-da-silva-tras-protestas\/","title":{"rendered":"Refrenda AMLO apoyo a Lula da Silva tras protestas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente\u00a0Andr\u00e9s Manuel L\u00f3pez Obrador\u00a0refrend\u00f3 su apoyo al mandatario de Brasil, Lula da Silva,\u00a0<strong>tras las protestas que se llevaron a cabo el domingo por\u00a0grupos\u00a0bolsonaristas<\/strong>\u00a0que tomaron\u00a0las sedes del Congreso, del Supremo\u00a0Tribunal Federal (STF).<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Pr\u00e1cticamente todos los gobiernos del mundo en rechazo a la actitud irresponsable, antidemocr\u00e1tica en Brasil y en favor del presidente Lula, esa es nuestra postura y coincidimos en esto&#8221;.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En\u00a0La Ma\u00f1anera desde Palacio Nacional,\u00a0el Presidente resalt\u00f3 que su gobierno seguir\u00e1 apoyando al presidente Lula &#8220;que fue electo democr\u00e1ticamente,\u00a0<strong>lo apoyan las fuerzas progresistas de Brasil, M\u00e9xico,<\/strong>\u00a0del continente americano&#8221;.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Es muy satisfactorio el que la solidaridad hacia el presidente Lula no sea nada m\u00e1s de pa\u00edses de Am\u00e9rica Latina y el Caribe sino que tambi\u00e9n el apoyo a la democracia en Brasil, al presidente Lula, tambi\u00e9n incluya a Canad\u00e1 a Estados Unidos y a pa\u00edses de todo el mundo&#8221;.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ante las protestas en ese pa\u00eds, L\u00f3pez Obrador dijo que es un hecho a destacar, &#8220;es un consenso de los pa\u00edses del continente americano, eso es muy bueno porque independientemente de las posturas pol\u00edticas y partidistas,&nbsp;<strong>se tiene que defender la democracia, respetar la voluntad del pueblo&#8221;.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El jefe del Ejecutivo mencion\u00f3 que dicho asunto no lo aplic\u00f3 con el presidente Biden mientras se trasladaba del AIFA a la Ciudad de M\u00e9xico porque, &#8220;ya no hubo necesidad de tratar el tema de Brasil porque \u00e9l ya se hab\u00eda pronunciado,\u00a0<strong>lo mismo el primer ministro Trudeau, lo mismo nosotros, lo hicieron&#8221;.\u00a0<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/amlo-refrenda-apoyo-a-lula-da-silva-tras-protestas-en-brasil\" data-type=\"URL\" data-id=\"https:\/\/www.milenio.com\/politica\/amlo-refrenda-apoyo-a-lula-da-silva-tras-protestas-en-brasil\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente\u00a0Andr\u00e9s Manuel L\u00f3pez Obrador\u00a0refrend\u00f3 su apoyo al mandatario de Brasil, Lula da Silva,\u00a0tras las protestas que se llevaron a cabo el domingo por\u00a0grupos\u00a0bolsonaristas\u00a0que tomaron\u00a0las sedes del Congreso, del Supremo\u00a0Tribunal Federal (STF). &#8220;Pr\u00e1cticamente todos los gobiernos del mundo en rechazo a la actitud irresponsable, antidemocr\u00e1tica en Brasil y en favor del presidente Lula, esa es [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":83048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[188,410,7272,162,13873],"class_list":["post-89412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-amlo","tag-apoyo","tag-lula-da-silva","tag-portada","tag-refrenda","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=89412"}],"version-history":[{"count":4,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89412\/revisions"}],"predecessor-version":[{"id":89416,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89412\/revisions\/89416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/83048"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=89412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=89412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=89412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}