{"id":89138,"date":"2023-01-06T10:54:41","date_gmt":"2023-01-06T16:54:41","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=89138"},"modified":"2023-01-06T10:54:42","modified_gmt":"2023-01-06T16:54:42","slug":"abre-peso-al-alza-y-se-enfila-a-romper-el-piso-de-19-18-por-dolar","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/01\/06\/abre-peso-al-alza-y-se-enfila-a-romper-el-piso-de-19-18-por-dolar\/","title":{"rendered":"Abre peso al alza y se enfila a romper el piso de 19.18 por d\u00f3lar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El peso sube la ma\u00f1ana de este viernes frente al d\u00f3lar y se apresta a cerrar la semana con ganancias, en medio de un optimismo generalizado entre los inversionistas ante una mejor\u00eda del panorama econ\u00f3mico en Estados Unidos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La moneda local extiende sus avances por quinta sesi\u00f3n consecutiva, en momentos en los que los operadores examinan con lupa un importante reporte de empleo de Estados Unidos que super\u00f3 las expectativas del mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El peso\u00a0opera en 19.2260 unidades por d\u00f3lar, con una apreciaci\u00f3n de un 0.46% frente al precio de referencia de Reuters del jueves, y se dirige a perforar otro soporte t\u00e9cnico importante de 19.1800 pesos por d\u00f3lar, seg\u00fan analistas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cLa s\u00f3lida creaci\u00f3n de empleo en Estados Unidos es una buena noticia para el consumo y la demanda por exportaciones mexicanas\u201d, dijo Banco Base en una nota enviada a clientes.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El informe del gobierno de Estados Unidos indic\u00f3 hoy viernes que la mayor econom\u00eda mundial mantuvo&nbsp;un fuerte ritmo de creaci\u00f3n de puestos de trabajo&nbsp;en diciembre, mientras que la tasa de desempleo cay\u00f3 al 3.5%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cantidad de estadounidenses que present\u00f3 nuevas\u00a0solicitudes de beneficios por desempleo\u00a0cay\u00f3 a un m\u00ednimo de tres meses la semana pasada, mientras que los despidos cayeron un 43% en diciembre, mostraron los datos de ayer jueves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.forbes.com.mx\/peso-abre-al-alza-y-se-enfila-a-romper-el-piso-de-19-18-por-dolar\/\" data-type=\"URL\" data-id=\"https:\/\/www.forbes.com.mx\/peso-abre-al-alza-y-se-enfila-a-romper-el-piso-de-19-18-por-dolar\/\">Forbes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El peso sube la ma\u00f1ana de este viernes frente al d\u00f3lar y se apresta a cerrar la semana con ganancias, en medio de un optimismo generalizado entre los inversionistas ante una mejor\u00eda del panorama econ\u00f3mico en Estados Unidos. La moneda local extiende sus avances por quinta sesi\u00f3n consecutiva, en momentos en los que los operadores [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":85490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[10089,7541,417,22337,416,9849,18552],"class_list":["post-89138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-abre","tag-alza","tag-dolar","tag-enfila","tag-peso","tag-piso","tag-romper","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=89138"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89138\/revisions"}],"predecessor-version":[{"id":89139,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89138\/revisions\/89139"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/85490"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=89138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=89138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=89138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}