{"id":89071,"date":"2023-01-05T14:56:55","date_gmt":"2023-01-05T20:56:55","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=89071"},"modified":"2023-01-05T14:56:57","modified_gmt":"2023-01-05T20:56:57","slug":"dice-fed-que-en-2023-puede-desvanecerse-el-avance-de-la-inflacion","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2023\/01\/05\/dice-fed-que-en-2023-puede-desvanecerse-el-avance-de-la-inflacion\/","title":{"rendered":"Dice Fed que en 2023 puede desvanecerse el avance de la inflaci\u00f3n"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El presidente de la Reserva Federal de St. Louis, James Bullard, dijo el jueves que el nuevo a\u00f1o finalmente podr\u00eda traer un alivio bienvenido en el frente de la inflaci\u00f3n.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Comit\u00e9 Federal de Mercado Abierto que establece las tasas \u201cha tomado medidas agresivas durante 2022, con aumentos continuos en la tasa de pol\u00edtica monetaria planificados para 2023, y esto ha devuelto las expectativas de inflaci\u00f3n a un nivel consistente con el objetivo de inflaci\u00f3n del 2% de la Fed\u201d, dijo Bullard en material preparado para una presentaci\u00f3n ante una reuni\u00f3n celebrada por la CFA Society de St. Louis.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cDurante 2023, la inflaci\u00f3n real probablemente seguir\u00e1 las expectativas de inflaci\u00f3n a un nivel m\u00e1s bajo a medida que la econom\u00eda real se normalice\u201d, afirm\u00f3.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Bullard no conect\u00f3 esa perspectiva con una orientaci\u00f3n espec\u00edfica sobre cambios en las tasas. Bullard ocup\u00f3 un puesto de voto en el FOMC durante 2022, en un a\u00f1o marcado por la campa\u00f1a hist\u00f3ricamente agresiva del banco central para elevar las tasas y reducir algunos de los niveles de inflaci\u00f3n m\u00e1s altos vistos en d\u00e9cadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eso hizo que el banco central aumentara su objetivo de tasa a un d\u00eda desde niveles cercanos a cero en marzo al rango actual de 4.25% a 4.50%.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fed elev\u00f3 el objetivo por \u00faltima vez en diciembre, subiendo 50 puntos b\u00e1sicos, y apunt\u00f3 a llegar a un 5,1% este a\u00f1o. Los funcionarios han dicho que donde sea que se detengan con las tasas, es probable que se mantengan por un tiempo a medida que se aseguran de que las presiones inflacionarias est\u00e1n disminuyendo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente:<a href=\"https:\/\/www.forbes.com.mx\/fed-dice-que-en-2023-puede-desvanecerse-el-avance-de-la-inflacion\/\" data-type=\"URL\" data-id=\"https:\/\/www.forbes.com.mx\/fed-dice-que-en-2023-puede-desvanecerse-el-avance-de-la-inflacion\/\"> Forbes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente de la Reserva Federal de St. Louis, James Bullard, dijo el jueves que el nuevo a\u00f1o finalmente podr\u00eda traer un alivio bienvenido en el frente de la inflaci\u00f3n. El Comit\u00e9 Federal de Mercado Abierto que establece las tasas \u201cha tomado medidas agresivas durante 2022, con aumentos continuos en la tasa de pol\u00edtica monetaria [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":53196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[7702,22329,2978],"class_list":["post-89071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-avance","tag-desvanecerse","tag-inflacion","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=89071"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89071\/revisions"}],"predecessor-version":[{"id":89072,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/89071\/revisions\/89072"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/53196"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=89071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=89071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=89071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}