{"id":82041,"date":"2022-11-10T09:54:48","date_gmt":"2022-11-10T15:54:48","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=82041"},"modified":"2022-11-10T09:54:49","modified_gmt":"2022-11-10T15:54:49","slug":"mexico-y-eu-acuerdan-mayor-seguridad-ante-drogas","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/11\/10\/mexico-y-eu-acuerdan-mayor-seguridad-ante-drogas\/","title":{"rendered":"M\u00e9xico y  EU acuerdan mayor seguridad ante drogas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La subsecretaria de Estado de Estados Unidos, Wendy Sherman, se reuni\u00f3 con el titular de Relaciones Exteriores, Marcelo Ebrard, durante su visita a M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un comunicado, el Departamento de Estado detall\u00f3 que los funcionarios \u201chablaron sobre los esfuerzos para fortalecer las cadenas de suministro de Am\u00e9rica del Norte y profundizar la colaboraci\u00f3n para abordar la amenaza global de las drogas sint\u00e9ticas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se\u00f1alaron que Sherman y Ebrard hablaron sobre la cooperaci\u00f3n para seguir fortaleciendo la seguridad en Am\u00e9rica del Norte, al igual que los compromisos asumidos en los di\u00e1logos Econ\u00f3mico y de Seguridad de Alto Nivel entre ambos pa\u00edses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s del canciller, Sherman tendr\u00e1 reuniones con la secretaria de Econom\u00eda, Raquel Buenrostro, y el titular de Hacienda, Rogelio Ram\u00edrez de la O.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, la subsecretaria tambi\u00e9n se reunir\u00e1 con l\u00edderes empresariales mexicanos, representantes de la comunidad LGBTQI+ y activistas enfocados en las desapariciones de personas en el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de su cuenta de Twitter, Sherman apunt\u00f3 que, \u201c<em>con una historia y un futuro compartidos, Estados Unidos y M\u00e9xico est\u00e1n comprometidos a promover nuestra visi\u00f3n de prosperidad y seguridad en Am\u00e9rica del Norte\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Departamento de Estado detall\u00f3 en el comunicado que el viaje de la subsecretaria por M\u00e9xico, que empez\u00f3 ayer mi\u00e9rcoles, terminar\u00e1 este jueves.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, el canciller resalt\u00f3 la importancia de la Cumbre de L\u00edderes de Am\u00e9rica del Norte, que se llevar\u00e1 a cabo en M\u00e9xico, ya que esto podr\u00e1 consolidar la regi\u00f3n en las pr\u00f3ximas d\u00e9cadas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A trav\u00e9s de un comunicado, el secretario afirm\u00f3 que \u201c<em>el mecanismo trilateral ser\u00e1 m\u00e1s importante que nunca debido al contexto geopol\u00edtico del mundo y al inicio de la nueva fase de la relaci\u00f3n entre M\u00e9xico y Estados Unidos\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual manera, el titular de la Secretar\u00eda de Relaciones Exteriores afirm\u00f3 que las prioridades del gobierno de M\u00e9xico, rumbo a la cumbre, son econom\u00eda, competitividad, relocalizaci\u00f3n de inversiones en materia de tecnolog\u00edas y seguridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente, la Canciller\u00eda detall\u00f3 que tambi\u00e9n se buscar\u00e1 abordar el tema migratorio, ya que se deben de buscar nuevas maneras de garantizar este derecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.elfinanciero.com.mx\/nacional\/2022\/11\/10\/acuerdan-eu-y-mexico-mayor-seguridad-ante-drogas\/\">El Financiero<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La subsecretaria de Estado de Estados Unidos, Wendy Sherman, se reuni\u00f3 con el titular de Relaciones Exteriores, Marcelo Ebrard, durante su visita a M\u00e9xico. A trav\u00e9s de un comunicado, el Departamento de Estado detall\u00f3 que los funcionarios \u201chablaron sobre los esfuerzos para fortalecer las cadenas de suministro de Am\u00e9rica del Norte y profundizar la colaboraci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":82042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[1201,2375,292,162],"class_list":["post-82041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-drogas","tag-estado-de-mexico","tag-mexico","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/82041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=82041"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/82041\/revisions"}],"predecessor-version":[{"id":82043,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/82041\/revisions\/82043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/82042"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=82041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=82041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=82041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}