{"id":7838,"date":"2021-03-16T12:21:26","date_gmt":"2021-03-16T18:21:26","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=7838"},"modified":"2021-03-16T22:46:16","modified_gmt":"2021-03-17T04:46:16","slug":"cargos-no-reconocidos-en-mi-tarjeta-bancaria","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/03\/16\/cargos-no-reconocidos-en-mi-tarjeta-bancaria\/","title":{"rendered":"Cargos no reconocidos en mi tarjeta bancaria&#8230;"},"content":{"rendered":"\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Lic. Francisco Javier P\u00e9rez Montes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante que Usted sepa, que cuando una instituci\u00f3n bancaria le otorga una tarjeta de cr\u00e9dito o de d\u00e9bito, le asigna un NIP (N\u00famero de Identificaci\u00f3n Personal), que consta de cuatro d\u00edgitos, el cual es confidencial y de su uso usted ser\u00e1 responsable, es por ello que a ninguna persona le debemos confiar este n\u00famero, pues debemos evitar que se haga mal uso de la tarjeta, por personas ajenas a nosotros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n debemos tener presente, que existen personas que ofrecen el tr\u00e1mite de una nueva tarjeta de cr\u00e9dito, y para ello le solicitan una copia de lado y lado, de alguna otra tarjeta bancaria con la que usted previamente cuente, lo cual debe evitarse, pues con los datos que contiene su tarjeta, como lo son el n\u00famero de tarjeta al frente y n\u00fameros al reverso, pueden hacer un mal uso, realizando compras por internet o pagos, que se ver\u00e1n reflejados en su pr\u00f3ximo estado de cuenta; ante esta situaci\u00f3n, es importante reportar su tarjeta ante el banco, a fin de evitar se siga haciendo un mal uso de ella, en detrimento de su patrimonio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando Usted pague con tarjeta bancaria, ya sea de d\u00e9bito o cr\u00e9dito, exija que la terminal donde se va a realizar el cargo est\u00e9 a la vista, pues de otra manera, su tarjeta puede ser clonada mediante alg\u00fan dispositivo electr\u00f3nico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nunca rebele datos\u00a0 personales ni de su tarjeta bancaria v\u00eda telef\u00f3nica, hoy en d\u00eda existen personas que se hacen pasar por funcionarios bancarios y le llaman para supuestamente verificar sus datos personales y de su tarjeta, recuerde que sus datos son confidenciales y que es preferible acudir directamente ante su ejecutivo bancario en la sucursal que le corresponda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si Usted fuera v\u00edctima de este tipo de fraudes, porque le hicieron cargos indebidos a su tarjeta, es necesario acudir ante la CONDUSEF (Comisi\u00f3n Nacional de Usuarios de Servicios Financieros) e interponer su queja, ya sea presencial o v\u00eda electr\u00f3nica, narrando los hechos y describiendo los cargos no reconocidos, a fin de que le sea solicitado su informe a la instituci\u00f3n bancaria y esta autoridad pueda determinar a trav\u00e9s de un dictamen t\u00e9cnico, si la queja es procedente o no; para el caso de ser procedente la queja, se deber\u00e1 demandar a la instituci\u00f3n bancaria en la v\u00eda ordinaria mercantil, el monto de los cargos no reconocidos y sus accesorios legales, para lo cual deber\u00e1 estar asistido de un abogado, pues tendr\u00e1 que acudir ante los tribunales a deducir su derecho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Recuerden que un consejo legal a tiempo, puede evitar problemas a futuro; siendo la intenci\u00f3n de esta columna, fomentar la cultura de prevenci\u00f3n, as\u00ed como dar a conocer las distintas problem\u00e1ticas legales que se presentan en nuestra sociedad, y que tienen que ser resueltas a trav\u00e9s de las distintas materias y especialidades del derecho.<\/p>\n\n\n\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>javi_montes72@hotmail.com<br>Cel. 2291 208735<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lic. Francisco Javier P\u00e9rez Montes Es importante que Usted sepa, que cuando una instituci\u00f3n bancaria le otorga una tarjeta de cr\u00e9dito o de d\u00e9bito, le asigna un NIP (N\u00famero de Identificaci\u00f3n Personal), que consta de cuatro d\u00edgitos, el cual es confidencial y de su uso usted ser\u00e1 responsable, es por ello que a ninguna persona [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":7840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1443],"tags":[1442],"class_list":["post-7838","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mi-consejo-legal","tag-franciscoperez","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/7838","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7838"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/7838\/revisions"}],"predecessor-version":[{"id":7841,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/7838\/revisions\/7841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/7840"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7838"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7838"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}