{"id":73624,"date":"2022-09-10T13:41:57","date_gmt":"2022-09-10T18:41:57","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=73624"},"modified":"2022-09-10T13:41:58","modified_gmt":"2022-09-10T18:41:58","slug":"ken-salazar-hace-balance-tras-un-ano-como-embajador-de-eu","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/09\/10\/ken-salazar-hace-balance-tras-un-ano-como-embajador-de-eu\/","title":{"rendered":"Ken Salazar hace balance tras un a\u00f1o como embajador de EU"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A un a\u00f1o de su llegada como embajador de EU en M\u00e9xico, Ken Salazar hizo un balance luego de concluir su visita a los 32 estados de la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El representante del gobierno de Joe Biden reconoci\u00f3 &#8220;la grandeza de M\u00e9xico, de su gente, cultura y paisajes&#8221;, pero tambi\u00e9n los retos entre ambos pa\u00edses.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;<em>En cada estado, me he reunido con gobernadores, alcaldes, funcionarios federales, el sector privado y la sociedad civil para trabajar en beneficio de nuestras naciones.\u00a0En el aniversario de mi primer a\u00f1o, tengo m\u00e1s optimismo que nunca de que nuestras naciones tendr\u00e1n un futuro compartido brillante, pr\u00f3spero y sustentable.<\/em><\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><em>En cada estado, me he reunido con gobernadores, alcaldes, funcionarios federales, el sector privado y la sociedad civil para trabajar en beneficio de nuestras naciones.\u00a0En el aniversario de mi primer a\u00f1o, tengo m\u00e1s optimismo que nunca de que nuestras naciones tendr\u00e1n un futuro compartido brillante, pr\u00f3spero y sustentable<\/em>&#8220;, destac\u00f3 Salazar en un comunicado.<\/p><\/blockquote>\n\n\n\n<h4 class=\"wp-block-heading\">Lucha contra narcotr\u00e1fico y la soberan\u00eda de M\u00e9xico<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, apuntala que &#8220;respetando la soberan\u00eda de M\u00e9xico&#8221;, EU &#8220;trabaja&nbsp;para ponerle un alto a las peligrosas organizaciones criminales que llevan corrupci\u00f3n y criminalidad a nuestros pa\u00edses. Falta mucho por hacer, incluyendo invertir mayores recursos para fortalecer la procuraci\u00f3n y el sistema de justicia en todos los niveles&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el mismo sentido, afirm\u00f3 que el Gobierno de los Estados Unidos est\u00e1 comprometido a frenar el tr\u00e1fico ilegal de armas para que no lleguen a nuestras comunidades en los dos pa\u00edses. &#8220;Cada a\u00f1o las autoridades estadounidenses decomisan m\u00e1s de 600 mil armas&#8221;, dijo Salazar, quien record\u00f3 que el Congreso de los Estados Unidos acaba de aprobar en junio la Ley para Detener el Tr\u00e1fico Ilegal de Armas de Fuego.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;<em>Para detener a las organizaciones criminales que ponen en riesgo a nuestras sociedades, incrementamos los esfuerzos de coordinaci\u00f3n con M\u00e9xico contra el fentanilo, el tr\u00e1fico de armas y el contrabando de personas<\/em>&#8220;, destac\u00f3 el embajador de EU.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, anunci\u00f3 que el 12 de diciembre se celebrar\u00e1 el bicentenario entre los Estados Unidos y M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/un-ano-de-su-llegada-como-embajador-de-eu-en-mexico-ken-salazar-hace-balance\">El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A un a\u00f1o de su llegada como embajador de EU en M\u00e9xico, Ken Salazar hizo un balance luego de concluir su visita a los 32 estados de la Rep\u00fablica. El representante del gobierno de Joe Biden reconoci\u00f3 &#8220;la grandeza de M\u00e9xico, de su gente, cultura y paisajes&#8221;, pero tambi\u00e9n los retos entre ambos pa\u00edses. &#8220;En [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":24643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[19169,5523,162],"class_list":["post-73624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-balance","tag-ken-salazar","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/73624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=73624"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/73624\/revisions"}],"predecessor-version":[{"id":73625,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/73624\/revisions\/73625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/24643"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=73624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=73624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=73624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}