{"id":72901,"date":"2022-09-05T16:09:01","date_gmt":"2022-09-05T21:09:01","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=72901"},"modified":"2022-09-05T16:09:02","modified_gmt":"2022-09-05T21:09:02","slug":"celebran-simpatizantes-de-morena-decision-de-posponer-debate-en-la-scjn","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/09\/05\/celebran-simpatizantes-de-morena-decision-de-posponer-debate-en-la-scjn\/","title":{"rendered":"Celebran simpatizantes de Morena decisi\u00f3n de posponer debate en la SCJN"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Luego de dos horas de debate de los ministros de la\u00a0<strong>Suprema Corte de Justicia de la Naci\u00f3n<\/strong>\u00a0(SCJN), la docena de simpatizantes de\u00a0<strong>Morena<\/strong>\u00a0que apoyan la prisi\u00f3n preventiva oficiosa celebraron la decisi\u00f3n de posponer el debate de discusi\u00f3n.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Dos o tres ministros nos dan la raz\u00f3n de que no se puede tocar el art\u00edculo 19 Constitucional. Uno de los ministros dijo que \u00e9l no es competente para quitarle unas hojas a la Constituci\u00f3n.\u00a0<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos ministros valientemente han dicho que aunque lo diga la Corte Interamericana deben cuidar la Constituci\u00f3n. Prevalece la Constituci\u00f3n por encima de la recomendaci\u00f3n. El \u00fanico que puede cambiar la Constituci\u00f3n es el poder legislativo&#8221;, mencionaron.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al grito de: \u00a1No pasar\u00e1\u00a1 y \u00a1El pueblo unido jam\u00e1s sera vencido! los manifestantes celebraron la decisi\u00f3n de posponer el debate sobre la prisi\u00f3n preventiva oficiosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.eluniversal.com.mx\/nacion\/prision-preventiva-oficiosa-simpatizantes-de-morena-celebran-decision-de-posponer-debate-en-la-scjn\" data-type=\"URL\" data-id=\"https:\/\/www.eluniversal.com.mx\/nacion\/prision-preventiva-oficiosa-simpatizantes-de-morena-celebran-decision-de-posponer-debate-en-la-scjn\">El Universal<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de dos horas de debate de los ministros de la\u00a0Suprema Corte de Justicia de la Naci\u00f3n\u00a0(SCJN), la docena de simpatizantes de\u00a0Morena\u00a0que apoyan la prisi\u00f3n preventiva oficiosa celebraron la decisi\u00f3n de posponer el debate de discusi\u00f3n. &#8220;Dos o tres ministros nos dan la raz\u00f3n de que no se puede tocar el art\u00edculo 19 Constitucional. Uno [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":1329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[7573,3808,10245,252,8259,3194,1380],"class_list":["post-72901","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-celebran","tag-debate","tag-decision","tag-morena","tag-posponer","tag-scjn","tag-simpatizantes","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/72901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=72901"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/72901\/revisions"}],"predecessor-version":[{"id":72905,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/72901\/revisions\/72905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/1329"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=72901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=72901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=72901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}