{"id":71266,"date":"2022-08-25T11:42:04","date_gmt":"2022-08-25T16:42:04","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=71266"},"modified":"2022-08-25T11:42:05","modified_gmt":"2022-08-25T16:42:05","slug":"realizara-experta-de-onu-sobre-desplazados-internos-visita-oficial-a-mexico","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/08\/25\/realizara-experta-de-onu-sobre-desplazados-internos-visita-oficial-a-mexico\/","title":{"rendered":"Realizar\u00e1 experta de ONU sobre desplazados internos visita oficial a M\u00e9xico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Relatora Especial sobre los derechos humanos de los desplazados internos por el Consejo de Derechos Humanos de las Naciones Unidas (ONU), Cecilia Jimenez-Damary,&nbsp;<strong>realizar\u00e1 una visita oficial a M\u00e9xico del 29 de agosto al 9 de septiembre, para evaluar la situaci\u00f3n de derechos humanos de este grupo en el pa\u00eds.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEl desplazamiento interno debido a la violencia o los desastres ha existido desde hace mucho tiempo en M\u00e9xico, aunque haya sido recientemente reconocido; se estima que actualmente hay miles de personas desplazadas internas en el pa\u00eds\u201d, se\u00f1al\u00f3 Jimenez-Damary.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Durante su visita, la experta de la ONU&nbsp;<strong>examinar\u00e1 los marcos jur\u00eddicos, normativos e institucionales vigentes<\/strong>&nbsp;para proteger los derechos de las personas desplazadas internas, y proyectos de ley relevantes actualmente en revisi\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jimenez-Damary visitar\u00e1 la Ciudad de M\u00e9xico y los estados de Chihuahua, Chiapas y Guerrero. Tambi\u00e9n se reunir\u00e1 con altos funcionarios de Gobierno, Naciones Unidas y otras organizaciones de derechos humanos, humanitarias y de desarrollo, sociedad civil, personas desplazadas internas y comunidades afectadas por el desplazamiento interno.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEsta visita me brinda una oportunidad \u00fanica y en el momento oportuno para recopilar informaci\u00f3n de primera mano sobre la situaci\u00f3n de los derechos humanos de las y los desplazados internos en el pa\u00eds, y en particular, para colaborar con el gobierno y otras partes interesadas en la prevenci\u00f3n, respuesta y soluciones duraderas al desplazamiento interno\u201d, mencion\u00f3.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La experta de la ONU presentar\u00e1 sus observaciones preliminares al final de su visita el 9 de septiembre en una conferencia de prensa y el informe completo sobre la visita de la Relatora Especial al Consejo de Derechos Humanos se dar\u00e1 a conocer en junio de 2023.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/experta-onu-desplazados-internos-hara-visita-oficial-mexico\" data-type=\"URL\" data-id=\"https:\/\/www.milenio.com\/politica\/experta-onu-desplazados-internos-hara-visita-oficial-mexico\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Relatora Especial sobre los derechos humanos de los desplazados internos por el Consejo de Derechos Humanos de las Naciones Unidas (ONU), Cecilia Jimenez-Damary,&nbsp;realizar\u00e1 una visita oficial a M\u00e9xico del 29 de agosto al 9 de septiembre, para evaluar la situaci\u00f3n de derechos humanos de este grupo en el pa\u00eds. \u201cEl desplazamiento interno debido a [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":60062,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[157],"tags":[11110,18668,3431,292,10076,513,15352,8868],"class_list":["post-71266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-desplazados","tag-experta","tag-internos","tag-mexico","tag-oficial","tag-onu","tag-realizara","tag-visita","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/71266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=71266"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/71266\/revisions"}],"predecessor-version":[{"id":71267,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/71266\/revisions\/71267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/60062"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=71266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=71266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=71266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}