{"id":6816,"date":"2021-03-06T21:48:27","date_gmt":"2021-03-07T03:48:27","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=6816"},"modified":"2021-03-06T21:50:54","modified_gmt":"2021-03-07T03:50:54","slug":"la-carta-de-dante","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/03\/06\/la-carta-de-dante\/","title":{"rendered":"La carta de Dante"},"content":{"rendered":"\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Por Mois\u00e9s Hern\u00e1ndez Yoldi<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La concentraci\u00f3n de poder es un desaf\u00edo en todo r\u00e9gimen, la historia nos muestra evidencia documentada de los graves da\u00f1os y excesos que se pueden cometer cuando el poder se concentra y no encuentra contrapesos en su ejercicio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Podemos definir el poder como la capacidad de producir cambios significativos en el estado de las cosas, directamente o a trav\u00e9s de terceros, mediante acciones u omisiones. El soci\u00f3logo Max Weber ya advert\u00eda de los peligros de la creciente concentraci\u00f3n del poder. Su disc\u00edpulo Robert Michels se\u00f1ala que las organizaciones modernas, tanto privadas como p\u00fablicas, suelen estar bajo el control de reducidos, pero poderosos grupos pol\u00edticos o financieros. Seg\u00fan Michels, los l\u00edderes son elegidos democr\u00e1ticamente pero tienden a integrarse en lo que Charles Wright Mills denomina las \u201c\u00e9lites del poder\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toda Democracia madura tiene de manera natural contrapesos que le permiten avanzar en su desarrollo. En M\u00e9xico estamos construyendo y consolidando una democracia, estamos aprendiendo a vivir en ella. En este proceso hemos constatado el valor de los contrapesos para que la vida democr\u00e1tica se desarrolle evitando concentraciones de poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oposici\u00f3n pol\u00edtica es un elemento b\u00e1sico y esencial en los reg\u00edmenes democr\u00e1ticos; su importancia radica en que son el factor de control y limitaci\u00f3n de los gobiernos en turno y la alternativa a la formaci\u00f3n de nuevos gobiernos. Dentro de un r\u00e9gimen democr\u00e1tico, la oposici\u00f3n tiene entre sus tareas la de mantener el equilibrio entre las intenciones de la autoridad y el apego a la legalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La oposici\u00f3n tiene tres funciones dentro de una democracia: colaboraci\u00f3n, control y contestaci\u00f3n. Una oposici\u00f3n s\u00f3lida no se construye solamente a partir de votos en contra de las propuestas presentadas por el Ejecutivo y su partido pol\u00edtico, sino tambi\u00e9n en la discusi\u00f3n con sus adversarios de los mecanismos con los que se solucionar\u00e1n las problem\u00e1ticas de un pa\u00eds. El pluralismo y la convivencia en el disenso son \u201cpresupuestos inexcusables de la democracia\u201d. La oposici\u00f3n debe buscar gobernar desde la colaboraci\u00f3n y asumir la responsabilidad de disentir y de apoyar buscando el mayor bienestar para la poblaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentido vale la pena retomar la carta que el senador Dante Delgado dirigi\u00f3 al presidente en d\u00edas pasados, en ella el experimentado pol\u00edtico veracruzano acusa al presidente L\u00f3pez Obrador de haber construido una oposici\u00f3n a su favor e intereses, pero no la que necesita el pa\u00eds. Delgado Ranauro va m\u00e1s all\u00e1 y lo acusa de construir, con las formas tradicionales de operaci\u00f3n pol\u00edtica, las condiciones para secuestrar al Congreso, capturar al Poder Judicial y restituir la presidencia imperial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la carta, Dante se da tiempo para fustigar al PAN y al PRI, a quienes califica de ingenuos, al aprobar las reformas que le permitir\u00e1n al presidente coartar la libertad de quienes disienten o se opongan a los intereses del r\u00e9gimen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dante Delgado advierte que: <em>\u201cFrente a este atentado a la democracia y a la divisi\u00f3n de poderes, los empresarios, desesperados y ofendidos, y los dirigentes de partido, ofuscados y desconcentrados, no logran entenderte, ni estudiarte, ni analizarte, ni valorarte como el ser pol\u00edtico que eres. Los tienes totalmente desorientados\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Y agrega: <em>\u201cLos provocas permanentemente para que sigan aturdidos: liberales contra conservadores, buenos contra malos, honestos contra corruptos, amigo del pueblo bueno contra la mafia del poder. Lo lamentable es que, sin excepci\u00f3n alguna, todas esas fuerzas de representaci\u00f3n real han aceptado tu desaf\u00edo de conmigo o contra m\u00ed. No advierten que tu objetivo es contrastarlos con un gobierno que, aunque inoperante, es cercano a la gente. Por esa raz\u00f3n no procuras acuerdos, insistes en diferenciarte de ellos, es tu timbre de orgullo, te sientes honrado y procuras cercan\u00eda con un pueblo que rechaz\u00f3 la forma en que ellos gobernaron los \u00faltimos 18 a\u00f1os\u201d.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalmente Dante es lapidario al momento de calificar a los l\u00edderes de los partidos opositores:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cDesafortunadamente, hoy nuestro pa\u00eds tiene a la generaci\u00f3n de dirigentes m\u00e1s mediocres y torpes de la historia. Acostumbrados a ser depositarios de un poder derivado, es decir, el que se delega de arriba hacia abajo, no saben c\u00f3mo reaccionar y no pueden comportarse a la altura del momento que vivimos porque no entienden lo que significa el poder generado, ese que se construye de abajo hacia arriba, el que se gana con esfuerzo y trabajo propio\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La carta de Dante no solo est\u00e1 dirigida al presidente L\u00f3pez Obrador, sus se\u00f1alamientos tienen varios destinatarios, se trata de la cr\u00edtica de un veterano de la pol\u00edtica, un hombre que ha transitado en las mism\u00edsimas entra\u00f1as del poder, formado y educado en la vieja escuela priista, la misma en la que se crio y cre\u00f3 Lopez Obrador, tal vez por eso y solo por eso, valdr\u00eda la pena tomarlo en cuenta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Mois\u00e9s Hern\u00e1ndez Yoldi La concentraci\u00f3n de poder es un desaf\u00edo en todo r\u00e9gimen, la historia nos muestra evidencia documentada de los graves da\u00f1os y excesos que se pueden cometer cuando el poder se concentra y no encuentra contrapesos en su ejercicio. Podemos definir el poder como la capacidad de producir cambios significativos en el [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":6818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[429],"tags":[430],"class_list":["post-6816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artillero","tag-moises-hernandez-yoldi","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/6816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6816"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/6816\/revisions"}],"predecessor-version":[{"id":6817,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/6816\/revisions\/6817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/6818"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=6816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=6816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}