{"id":66808,"date":"2022-07-26T11:03:32","date_gmt":"2022-07-26T16:03:32","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=66808"},"modified":"2022-07-26T11:03:33","modified_gmt":"2022-07-26T16:03:33","slug":"urge-amlo-a-hacienda-levantar-portal-de-compranet","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/07\/26\/urge-amlo-a-hacienda-levantar-portal-de-compranet\/","title":{"rendered":"Urge AMLO a Hacienda levantar portal de Compranet"},"content":{"rendered":"\n<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador urgi\u00f3 al secretario de Hacienda, Rogelio Ram\u00edrez de la O, a restituir el portal del gobierno Compranet, que tuvo que ser dado de baja, indefinidamente, presuntamente por un problema t\u00e9cnico.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cAyer le habl\u00e9 al secretario de Hacienda para que nos diera una explicaci\u00f3n. Han tenido un problema t\u00e9cnico y ya le urg\u00ed que se resuelva porque ya nuestros adversarios est\u00e1n imaginando con su mente cochambrosa cosas que no son.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cYa ven que, con todo el respeto al le\u00f3n, \u00e9l cree que todos son peludos, vamos a informar, pero fue un problema t\u00e9cnico, no se oculta nada, adem\u00e1s qu\u00e9 caso tendr\u00eda tirar una p\u00e1gina si luego se tiene que reestablecer y cu\u00e1ntos cr\u00edticos tenemos, conservadores, expertos en manejo de la computaci\u00f3n e internet, de todo, pero es un asunto t\u00e9cnico que ya se va a resolver\u201d, expuso el mandatario federal en conferencia de prensa desde Palacio Nacional.<\/p><\/blockquote>\n\n\n\n<p>El pasado 16 de julio, la Secretar\u00eda de Hacienda y Cr\u00e9dito P\u00fablico (SHCP) inform\u00f3 que la operaci\u00f3n de Compranet, una plataforma de compras de bienes y servicios del gobierno federal, tuvo que ser suspendida por diversas fallas t\u00e9cnicas en la infraestructura que alberga el sitio.<\/p>\n\n\n\n<p>Hace unos d\u00edas, la dependencia federal autoriz\u00f3 a todas las dependencias federales desahogar sus procedimientos de contrataci\u00f3n de manera presencial, tras la ca\u00edda de Compranet.<\/p>\n\n\n\n<p>Al respecto, el&nbsp;Instituto Nacional de Transparencia, Acceso a la Informaci\u00f3n y Protecci\u00f3n de DatosPersonales&nbsp;(INAI) hizo un llamado a Hacienda a que restablezca a la brevedad el sistema electr\u00f3nico de compras p\u00fablicas.<\/p>\n\n\n\n<p>En un comunicado, el Instituto se\u00f1al\u00f3 que una de las obligaciones de la dependencias y entidades es publicar y mantener actualizada, en los respectivos medios electr\u00f3nicos, la informaci\u00f3n relacionada con los procesos de contrataci\u00f3n.<\/p>\n\n\n\n<p>Fuente: <em><a href=\"https:\/\/www.forbes.com.mx\/amlo-urge-a-hacienda-levantar-portal-de-compranet\/\" data-type=\"URL\" data-id=\"https:\/\/www.forbes.com.mx\/amlo-urge-a-hacienda-levantar-portal-de-compranet\/\">Forbes<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador urgi\u00f3 al secretario de Hacienda, Rogelio Ram\u00edrez de la O, a restituir el portal del gobierno Compranet, que tuvo que ser dado de baja, indefinidamente, presuntamente por un problema t\u00e9cnico. \u201cAyer le habl\u00e9 al secretario de Hacienda para que nos diera una explicaci\u00f3n. Han tenido un problema t\u00e9cnico y [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":54481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[188,5980,2698,14604,17641,15758],"class_list":["post-66808","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-amlo","tag-compranet","tag-hacienda","tag-levantar","tag-portal","tag-urge","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/66808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=66808"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/66808\/revisions"}],"predecessor-version":[{"id":66811,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/66808\/revisions\/66811"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/54481"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=66808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=66808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=66808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}