{"id":6440,"date":"2021-03-03T13:50:25","date_gmt":"2021-03-03T19:50:25","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=6440"},"modified":"2021-03-03T13:50:26","modified_gmt":"2021-03-03T19:50:26","slug":"vacunacion-del-80-adultos-mayores-en-puente-nacional","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/03\/03\/vacunacion-del-80-adultos-mayores-en-puente-nacional\/","title":{"rendered":"Reportan vacunaci\u00f3n del 80% de adultos mayores en Puente Nacional"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Sam Ojeda \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Xalapa.- En el municipio de Puente Nacional el 80 por ciento de la poblaci\u00f3n adulta mayor ya fue vacunada contra el covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esto fue informado por el gobernador de Veracruz, Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez, quien dijo es parte de la primera etapa del Plan Nacional de Vacunaci\u00f3n para este municipio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de la sesi\u00f3n de la mesa de la Coordinaci\u00f3n para la Construcci\u00f3n de la Paz, el mandatario dio a conocer que se instal\u00f3 en la localidad de Tamarindo un m\u00f3dulo de la Secretar\u00eda de Seguridad P\u00fablica (SSPI) y la Guardia Nacional para reforzar la seguridad de esta zona.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cNos es grato constatar que el Plan Nacional de Vacunaci\u00f3n en su primera etapa en este municipio ya protegi\u00f3 al 80% de la poblaci\u00f3n adulta mayor y que en coordinaci\u00f3n los tres \u00f3rdenes de gobierno se ha instalado en Tamarindo el m\u00f3dulo de operaciones conjuntas de SSP y Guardia Nacional\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n inform\u00f3 que el delegado federal de la Secretar\u00eda del Bienestar, Manuel Huerta Ladr\u00f3n de Guevara, reinicio la entrega de apoyos a pescadores registrados en el programa \u201cBienpesca\u201d a nivel estatal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sam Ojeda \/ NV Noticias Xalapa.- En el municipio de Puente Nacional el 80 por ciento de la poblaci\u00f3n adulta mayor ya fue vacunada contra el covid-19. Esto fue informado por el gobernador de Veracruz, Cuitl\u00e1huac Garc\u00eda Jim\u00e9nez, quien dijo es parte de la primera etapa del Plan Nacional de Vacunaci\u00f3n para este municipio. Luego [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":4750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[156],"tags":[1390,1956,809,180],"class_list":["post-6440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-adultos-mayores","tag-puente-nacional","tag-vacunacion","tag-veracruz","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/6440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=6440"}],"version-history":[{"count":2,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/6440\/revisions"}],"predecessor-version":[{"id":6442,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/6440\/revisions\/6442"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/4750"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=6440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=6440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=6440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}