{"id":61249,"date":"2022-06-23T11:47:35","date_gmt":"2022-06-23T16:47:35","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=61249"},"modified":"2022-06-23T11:47:36","modified_gmt":"2022-06-23T16:47:36","slug":"se-reunira-presidente-de-espana-con-biden-previo-a-cumbre-de-la-otan-en-madrid","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/06\/23\/se-reunira-presidente-de-espana-con-biden-previo-a-cumbre-de-la-otan-en-madrid\/","title":{"rendered":"Se reunir\u00e1 presidente de Espa\u00f1a con Biden previo a cumbre de la OTAN en Madrid"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>El gobierno de Espa\u00f1a confirm\u00f3<\/strong>&nbsp;este jueves&nbsp;<strong>que el presidente Pedro S\u00e1nchez se reunir\u00e1 con el mandatario de Estados Unidos, Joe Biden, as\u00ed como con el rey Felipe VI,&nbsp;<\/strong>antes de la cumbre de la OTAN que se celebrar\u00e1 en Madrid la pr\u00f3xima semana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue el ministro de la Presidencia, F\u00e9lix Bola\u00f1os, quien confirm\u00f3 que el encuentro entre Biden y S\u00e1nchez ser\u00e1 el pr\u00f3ximo martes a primera hora de la tarde sin precisar m\u00e1s detalles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Biden viajar\u00e1 a Madrid tras la cumbre del G7 que tendr\u00e1 lugar del 26 al 28 de junio en Alemania<\/strong>, y antes de que d\u00e9 comienzo la cumbre de la Alianza Atl\u00e1ntica el pr\u00f3ximo mi\u00e9rcoles 29 de junio, seg\u00fan adelant\u00f3 ayer un funcionario de la Casa Blanca a la prensa de su pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Esta ser\u00e1 la primera vez que Pedro S\u00e1nchez y Felipe VI mantengan una reuni\u00f3n bilateral en privado con Biden<\/strong>&nbsp;desde que tom\u00f3 posesi\u00f3n como presidente de Estados Unidos en enero de 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e1nchez y Biden conversaron el pasado martes por tel\u00e9fono durante 20 minutos. Charlaron sobre la relevancia de la cumbre para el futuro de la OTAN.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cumbre de la OTAN se realizar\u00e1 en Madrid el 29 y 30 de junio. La ciudad estar\u00e1 vigilada por 10 mil agentes de las Fuerzas y Cuerpos de Seguridad de Espa\u00f1a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por aire, el gobierno avanz\u00f3 el despliegue de artiller\u00eda antia\u00e9rea, aviones de la OTAN, helic\u00f3pteros y aparatos de combate listos para despegar ante cualquier amenaza, as\u00ed como la activaci\u00f3n de sistemas contra aeronaves no tripuladas. No obstante, evit\u00f3 confirmar si se cerrar\u00e1 el espacio a\u00e9reo de Madrid.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/internacional\/biden-confirma-reunion-con-presidente-de-espana\" data-type=\"URL\" data-id=\"https:\/\/www.milenio.com\/internacional\/biden-confirma-reunion-con-presidente-de-espana\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de Espa\u00f1a confirm\u00f3&nbsp;este jueves&nbsp;que el presidente Pedro S\u00e1nchez se reunir\u00e1 con el mandatario de Estados Unidos, Joe Biden, as\u00ed como con el rey Felipe VI,&nbsp;antes de la cumbre de la OTAN que se celebrar\u00e1 en Madrid la pr\u00f3xima semana. Fue el ministro de la Presidencia, F\u00e9lix Bola\u00f1os, quien confirm\u00f3 que el encuentro entre [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":18124,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[181],"tags":[16342,593,182,592,411,15034],"class_list":["post-61249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-cumbre-de-la-otan","tag-espana","tag-joe-biden","tag-madrid","tag-presidente","tag-se-reunira","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/61249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=61249"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/61249\/revisions"}],"predecessor-version":[{"id":61252,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/61249\/revisions\/61252"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/18124"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=61249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=61249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=61249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}