{"id":58206,"date":"2022-06-06T08:56:12","date_gmt":"2022-06-06T13:56:12","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=58206"},"modified":"2022-06-06T08:56:13","modified_gmt":"2022-06-06T13:56:13","slug":"claudicar-ante-el-poder","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/06\/06\/claudicar-ante-el-poder\/","title":{"rendered":"Claudicar ante el poder"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Mois\u00e9s Hern\u00e1ndez Yoldi<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una cosa es la disponibilidad y voluntad al di\u00e1logo, y otra claudicar ante un gobierno que se ha caracterizado por su incompetencia y soberbia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El papel de los organismos empresariales es defender la agenda de sus agremiados. Asumirse como un contrapeso natural ante el poder pol\u00edtico, acompa\u00f1ar las buenas decisiones en favor del Estado y se\u00f1alar y criticar aquellas que frenen la inversi\u00f3n y entorpezcan el crecimiento econ\u00f3mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes usan a los organismos empresariales para beneficio propio, traicionan la confianza de sus representados y fallan en su encomienda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El servilismo le ha hecho mucho da\u00f1o a Veracruz, repasemos la historia reciente:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gobernatura imperial<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el Alemanismo, el sector empresarial, casi por completo, adul\u00f3 y festej\u00f3 a un gobierno despilfarrador, que hizo gala de opulencia y poca eficiencia, eso s\u00ed, elegante y glamoroso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno populista<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el Fidelato, uno de los m\u00e1s oscuros y siniestros gobiernos que ha tenido Veracruz, se festej\u00f3 el populismo llevado a su m\u00e1xima expresi\u00f3n, conduciendo al Estado a niveles de endeudamiento insostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No fueron pocos los empresarios y organismos empresariales los que fueron usados y beneficiados por un gobierno que adem\u00e1s de corrupto, fue corruptor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El gobierno de la locura<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el delirante bacanal del Duartismo, el Estado toc\u00f3 fondo, el nivel de degradaci\u00f3n y descomposici\u00f3n pol\u00edtica y social fue de esc\u00e1ndalo, nuevamente, no fueron pocos los empresarios y c\u00e1maras empresariales los que se beneficiaron de las locuras y excesos de ese desgobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando parec\u00eda que habr\u00edamos aprendido la lecci\u00f3n, aparecen escenas como estas, empresarios y organismos empresariales, haciendo las veces de cortesanos y aduladores, ante un gobierno que mantiene al Estado en el rezago y el subdesarrollo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Datos:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz ocupa el lugar 27 de 32 Estados en el \u00edndice de competitividad (IMCO).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El PIB de Veracruz decreci\u00f3 de 827 millones de pesos en 2019 a 741,69; de acuerdo a estimaciones del Observatorio de Finanzas P\u00fablicas, se espera que el Estado podr\u00e1 recuperarse hasta 2027.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Di\u00e1logo y colaboraci\u00f3n s\u00ed, sometiemiento y servilismo no.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">PD: Menci\u00f3n aparte merece la autoritaria y soberbia mini gubernatura Yunista, caracterizada por la imposici\u00f3n y la persecuci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mois\u00e9s Hern\u00e1ndez Yoldi Una cosa es la disponibilidad y voluntad al di\u00e1logo, y otra claudicar ante un gobierno que se ha caracterizado por su incompetencia y soberbia. El papel de los organismos empresariales es defender la agenda de sus agremiados. Asumirse como un contrapeso natural ante el poder pol\u00edtico, acompa\u00f1ar las buenas decisiones en favor [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":58207,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[429],"tags":[430],"class_list":["post-58206","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artillero","tag-moises-hernandez-yoldi","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/58206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=58206"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/58206\/revisions"}],"predecessor-version":[{"id":58208,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/58206\/revisions\/58208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/58207"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=58206"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=58206"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=58206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}