{"id":55863,"date":"2022-05-22T11:13:24","date_gmt":"2022-05-22T16:13:24","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=55863"},"modified":"2022-05-22T11:13:25","modified_gmt":"2022-05-22T16:13:25","slug":"se-podria-impugnar-la-extincion-del-fideicomiso-del-acuario-de-veracruz","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/05\/22\/se-podria-impugnar-la-extincion-del-fideicomiso-del-acuario-de-veracruz\/","title":{"rendered":"Se podr\u00eda impugnar la extinci\u00f3n del fideicomiso del Acuario de Veracruz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla | NV Noticias<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz. &#8211; El Acuario de Veracruz podr\u00eda impugnar la extinci\u00f3n del fideicomiso, se\u00f1al\u00f3 Gilberto Far\u00edas Morales, presidente del Colegio de Abogados Penalistas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si afecta la econom\u00eda de Veracruz y la generaci\u00f3n de empleo, podr\u00eda interponerse el recurso mencionado, pero sobre todo ante la forma en que se efectu\u00f3 el cambio de administraci\u00f3n del lugar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que se pueden analizar las condiciones laborales de los colaboradores, pues ya se anunci\u00f3 p\u00fablicamente que ser\u00e1n liquidados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No descart\u00f3 que se emprendan acciones legales, luego de que en marzo de 2020, se public\u00f3 un acuerdo en la Gaceta Oficial del Estado, determinando la no extinci\u00f3n del fideicomiso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que durante 30 a\u00f1os el Acuario de Veracruz fue administrado por un patronato compuesto por empresarios veracruzanos y no hubo queja alguna.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s son empresarios serios y reconocidos quienes seguramente habr\u00e1n de emprender acciones legales y conducentes o en su caso las negociaciones que consideren.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Insisti\u00f3 en que est\u00e1 el antecedente de la no extinci\u00f3n del fideicomiso.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cTengo mis dudas, pues tenemos como ejemplos el estadio Luis Pirata Fuente, el auditorio Benito Ju\u00e1rez y el World Trade Center que est\u00e1n sin mantenimiento luego de que los tomara el estado para administrarlos\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ahora ser\u00e1 la Procuradur\u00eda del Medio Ambiente del Estado de Veracruz quien administre el lugar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla | NV Noticias&nbsp; Veracruz. &#8211; El Acuario de Veracruz podr\u00eda impugnar la extinci\u00f3n del fideicomiso, se\u00f1al\u00f3 Gilberto Far\u00edas Morales, presidente del Colegio de Abogados Penalistas. Si afecta la econom\u00eda de Veracruz y la generaci\u00f3n de empleo, podr\u00eda interponerse el recurso mencionado, pero sobre todo ante la forma en que se efectu\u00f3 el cambio [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":55864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[14644,14877],"class_list":["post-55863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-acuario-de-veracruz","tag-fideicomiso","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/55863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=55863"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/55863\/revisions"}],"predecessor-version":[{"id":55865,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/55863\/revisions\/55865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/55864"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=55863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=55863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=55863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}