{"id":55010,"date":"2022-05-16T13:44:25","date_gmt":"2022-05-16T18:44:25","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=55010"},"modified":"2022-05-16T13:44:26","modified_gmt":"2022-05-16T18:44:26","slug":"medicos-cubanos-trabajaran-en-regiones-donde-especialistas-mexicanos-no-quieren-amlo","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/05\/16\/medicos-cubanos-trabajaran-en-regiones-donde-especialistas-mexicanos-no-quieren-amlo\/","title":{"rendered":"M\u00e9dicos cubanos trabajar\u00e1n en regiones donde especialistas mexicanos no quieren: AMLO"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador justific\u00f3 este lunes la decisi\u00f3n de su gobierno de contratar a alrededor de 500 m\u00e9dicos especialistas cubanos al se\u00f1alar que es para cubrir la falta de atenci\u00f3n en las zonas m\u00e1s pobres del pa\u00eds y donde los profesionistas mexicanos no quieren laborar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mandatario federal expuso que dicha decisi\u00f3n se tom\u00f3 con base en un muestreo de los m\u00e9dicos mexicanos y su negativa de prestar atenci\u00f3n en zonas marginadas y rurales donde la atenci\u00f3n de especialistas es necesaria.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cEstamos contratando a todos los m\u00e9dicos pero como ya sabemos que no vamos a tener para cubrir toda la red de centros de salud y unidades m\u00e9dicas rurales, de hospitales, pues por eso ya estamos haciendo este convenio de traer 500 m\u00e9dicos\u201d, expuso el jefe del Ejecutivo federal en conferencia de prensa desde Palacio Nacional.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Desde que se dio el anuncio, en el marco de la visita que realiz\u00f3 L\u00f3pez Obrador a la Isla la semana pasada y donde suscribi\u00f3 el acuerdo con el presidente cubano Miguel D\u00edaz-Canel, m\u00e9dicos mexicanos han reprochado que el gobierno federal no los contrate para brindar servicios al sistema de salud.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cAhora \u00bfpor qu\u00e9 traer m\u00e9dicos de Cuba? Contestamos, porque no tenemos m\u00e9dicos, porque el sistema de corrupci\u00f3n que defendieron esos m\u00e9dicos, que firman esos m\u00e9dicos, dej\u00f3 de invertir en la educaci\u00f3n p\u00fablica\u201d, acus\u00f3 el mandatario federal.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.forbes.com.mx\/medicos-cubanos-trabajaran-en-regiones-donde-especialistas-mexicanos-no-quieren-amlo\/\" data-type=\"URL\" data-id=\"https:\/\/www.forbes.com.mx\/medicos-cubanos-trabajaran-en-regiones-donde-especialistas-mexicanos-no-quieren-amlo\/\">Forbes<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador justific\u00f3 este lunes la decisi\u00f3n de su gobierno de contratar a alrededor de 500 m\u00e9dicos especialistas cubanos al se\u00f1alar que es para cubrir la falta de atenci\u00f3n en las zonas m\u00e1s pobres del pa\u00eds y donde los profesionistas mexicanos no quieren laborar. El mandatario federal expuso que dicha decisi\u00f3n [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":51319,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[188,5029,9705,317,257,14849,14848,11204],"class_list":["post-55010","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-amlo","tag-cubanos","tag-especialistas","tag-medicos","tag-mexicanos","tag-no-quieren","tag-regiones","tag-trabajaran","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/55010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=55010"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/55010\/revisions"}],"predecessor-version":[{"id":55011,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/55010\/revisions\/55011"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/51319"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=55010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=55010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=55010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}