{"id":53788,"date":"2022-05-08T12:34:51","date_gmt":"2022-05-08T17:34:51","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=53788"},"modified":"2022-05-08T12:34:52","modified_gmt":"2022-05-08T17:34:52","slug":"firman-mexico-y-cuba-acuerdo-bilateral-de-salud-para-emergencias-sanitarias","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/05\/08\/firman-mexico-y-cuba-acuerdo-bilateral-de-salud-para-emergencias-sanitarias\/","title":{"rendered":"Firman M\u00e9xico y Cuba acuerdo bilateral de salud para emergencias sanitarias"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobierno de M\u00e9xico firm\u00f3 con el r\u00e9gimen cubano un acuerdo de cooperaci\u00f3n bilateral en materia de salud con el objetivo de combatir emergencias sanitarias. Lo anterior pese a la pol\u00e9mica generada en 2020 por la contrataci\u00f3n de m\u00e9dicos cubanos por parte de M\u00e9xico para combatir la pandemia del coronavirus, en los que se destinaron m\u00e1s de 250 millones de pesos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el \u00faltima d\u00eda de su gira de trabajo por el extranjero -la cual comenz\u00f3 desde el pasado 5 de mayo-, el presidente Andr\u00e9s Manuel L\u00f3pez Obrador sostuvo una reuni\u00f3n con el dictador cubano, Miguel D\u00edaz-Canel, en el Palacio de la Revoluci\u00f3n donde fue recibido con honores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En el acto presidi\u00f3 el secretario de Salud, Jorge Alcocer Varela, por parte de M\u00e9xico, y el almirante Jos\u00e9 Rafael Ojeda Dur\u00e1n, secretario de la Marina, por la parte cubana, as\u00ed como autoridades del r\u00e9gimen de Cuba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este acuerdo expresa la voluntad de fortalecer los lazos hist\u00f3ricos entre el r\u00e9gimen cubano y el gobierno de M\u00e9xico, as\u00ed como intensificar las actividades bilaterales, promover la cooperaci\u00f3n frente a los estragos derivados de la actual pandemia y colaborar en la atenci\u00f3n de crisis sanitarias y epidemias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.infobae.com\/america\/mexico\/2022\/05\/08\/mexico-firmo-con-el-regimen-cubano-acuerdo-bilateral-de-salud-para-emergencias-sanitarias-pese-a-polemica-previa\/\">Infobae<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de M\u00e9xico firm\u00f3 con el r\u00e9gimen cubano un acuerdo de cooperaci\u00f3n bilateral en materia de salud con el objetivo de combatir emergencias sanitarias. Lo anterior pese a la pol\u00e9mica generada en 2020 por la contrataci\u00f3n de m\u00e9dicos cubanos por parte de M\u00e9xico para combatir la pandemia del coronavirus, en los que se destinaron [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":53790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[158],"tags":[2468,2501,14530,292,162],"class_list":["post-53788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-acuerdo","tag-cuba","tag-emergencias-sanitarias","tag-mexico","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=53788"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53788\/revisions"}],"predecessor-version":[{"id":53789,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53788\/revisions\/53789"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/53790"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=53788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=53788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=53788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}