{"id":53768,"date":"2022-05-08T11:17:17","date_gmt":"2022-05-08T16:17:17","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=53768"},"modified":"2022-05-08T11:17:18","modified_gmt":"2022-05-08T16:17:18","slug":"se-destapa-lula-da-silva-como-candidato-presidencial","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/05\/08\/se-destapa-lula-da-silva-como-candidato-presidencial\/","title":{"rendered":"Se \u2018destapa\u2019 Lula da Silva como candidato presidencial"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El exmandatario\u00a0brasile\u00f1o Luiz In\u00e1cio Lula da Silva\u00a0lanz\u00f3 este s\u00e1bado su candidatura para las elecciones presidenciales de octubre con un mensaje de\u00a0\u201cesperanza\u201d y dispuesto a hacer \u201cla mayor revoluci\u00f3n pac\u00edfica\u201d\u00a0de la historia de Brasil.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cQueremos volver para que nadie nunca m\u00e1s ose desafiar la democracia y para que el fascismo sea devuelto a la alcantarilla\u201d, dijo Lula en un acto en un centro de convenciones de Sao Paulo, donde estuvo arropado por cientos de militantes, parlamentarios, artistas y representantes sindicales y sociales.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Trajeado, pero sin corbata, el exjefe de Estado (2003-2010), favorito para las\u00a0elecciones del pr\u00f3ximo 2 de octubre,\u00a0ley\u00f3 un discurso de forma solemne, con una enorme bandera de Brasil de fondo, cuyos colores verde y amarillo se los han apropiado la militancia bolsonarista en los \u00faltimos a\u00f1os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lula quiso dejar un\u00a0mensaje de \u201cpaz\u201d y \u201camor\u201d frente a la \u201camenaza totalitaria,\u00a0el odio, la violencia, la discriminaci\u00f3n, la exclusi\u00f3n que pesan sobre\u201d el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En toda su intervenci\u00f3n no hizo menci\u00f3n directa al actual gobernante, Jair Bolsonaro, su mayor adversario pol\u00edtico y quien aparece segundo en los sondeos con un 30 por ciento de las intenciones de voto, frente al cerca del 45 por ciento que otorgan a Lula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunque el\u00a0l\u00edder ultraderechista,\u00a0de forma impl\u00edcita, estuvo presente en cada una de sus palabras.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cTodo lo que hicimos y el pueblo brasile\u00f1o conquist\u00f3 est\u00e1 siendo destruido por el actual gobierno (&#8230;) Es m\u00e1s que urgente restaurar la soberan\u00eda de Brasil \u201c, sentenci\u00f3.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.elfinanciero.com.mx\/mundo\/2022\/05\/07\/lula-da-silva-se-destapa-como-candidato-presidencial-promete-revolucion-pacifica-en-brasil\/\">El Financiero<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El exmandatario\u00a0brasile\u00f1o Luiz In\u00e1cio Lula da Silva\u00a0lanz\u00f3 este s\u00e1bado su candidatura para las elecciones presidenciales de octubre con un mensaje de\u00a0\u201cesperanza\u201d y dispuesto a hacer \u201cla mayor revoluci\u00f3n pac\u00edfica\u201d\u00a0de la historia de Brasil. \u201cQueremos volver para que nadie nunca m\u00e1s ose desafiar la democracia y para que el fascismo sea devuelto a la alcantarilla\u201d, dijo [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":53769,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[181],"tags":[1976,7272],"class_list":["post-53768","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-brasil","tag-lula-da-silva","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=53768"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53768\/revisions"}],"predecessor-version":[{"id":53770,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53768\/revisions\/53770"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/53769"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=53768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=53768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=53768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}