{"id":53150,"date":"2022-05-04T12:19:45","date_gmt":"2022-05-04T17:19:45","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=53150"},"modified":"2022-05-04T12:19:45","modified_gmt":"2022-05-04T17:19:45","slug":"no-pararan-los-cortes-electricos-hasta-que-se-cambie-la-infraestructura","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/05\/04\/no-pararan-los-cortes-electricos-hasta-que-se-cambie-la-infraestructura\/","title":{"rendered":"No parar\u00e1n los cortes el\u00e9ctricos hasta que se cambie la infraestructura"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los usuarios de la Comisi\u00f3n Federal de Electricidad seguir\u00e1n presentando cortes de energ\u00eda el\u00e9ctrica, sobre todo quienes habitan en colonias cuyas instalaciones el\u00e9ctricas son antiguas, advirti\u00f3 Pedro Aguilar Pizarro, vicepresidente nacional del sector el\u00e9ctrico de la C\u00e1mara Mexicana de la Industria de la Construcci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hay que mencionar que en la semana varias colonias tuvieron interrupciones de corriente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ante ello Aguilar Pizarro record\u00f3 que colonias como Centro tienen instalaciones de m\u00e1s de 30 a\u00f1os de antig\u00fcedad.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aunado a ello no se les ha dado el mantenimiento adecuado.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201c<em>Los apagones son resultado de esto, si por tantos a\u00f1os no se ha dado mantenimiento a las instalaciones de CFE pues con toda seguridad las fallas ser\u00e1n continuas. Hoy que se est\u00e1n cambiando las l\u00edneas a\u00e9reas por subterr\u00e1neas y modificando transformadores de 20, 30 o 40 a\u00f1os de uso por nuevos permitir\u00e1 ir mejorando el servicio<\/em>\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que fortaleciendo a la CFE se puede tener mejor infraestructura, menor compra de energ\u00eda y mayor generaci\u00f3n de energ\u00edas limpias.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201c<em>De cualquier manera si se realiza una inversi\u00f3n sustantiva dentro de la industria el\u00e9ctrica que maneja la CFE se va a robustecer<\/em>\u201d.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Insisti\u00f3 que s\u00f3lo renovando la infraestructura del sector el\u00e9ctrico se podr\u00e1 ofrecer mejor servicio al usuario.\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias Los usuarios de la Comisi\u00f3n Federal de Electricidad seguir\u00e1n presentando cortes de energ\u00eda el\u00e9ctrica, sobre todo quienes habitan en colonias cuyas instalaciones el\u00e9ctricas son antiguas, advirti\u00f3 Pedro Aguilar Pizarro, vicepresidente nacional del sector el\u00e9ctrico de la C\u00e1mara Mexicana de la Industria de la Construcci\u00f3n. Hay que mencionar que en la [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":53152,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[821,6905,180],"class_list":["post-53150","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-cfe","tag-cortes-de-energia","tag-veracruz","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=53150"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53150\/revisions"}],"predecessor-version":[{"id":53153,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/53150\/revisions\/53153"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/53152"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=53150"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=53150"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=53150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}