{"id":49165,"date":"2022-04-10T15:19:34","date_gmt":"2022-04-10T20:19:34","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=49165"},"modified":"2022-04-10T15:19:35","modified_gmt":"2022-04-10T20:19:35","slug":"el-desprecio-a-la-democracia","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/04\/10\/el-desprecio-a-la-democracia\/","title":{"rendered":"El desprecio a la democracia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este domingo se efectuar\u00e1 el refer\u00e9ndum de revocaci\u00f3n de mandato, un ejercicio democr\u00e1tico de participaci\u00f3n directa in\u00e9dito en la historia moderna de M\u00e9xico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El refer\u00e9ndum deber\u00eda ser un avance en la construcci\u00f3n de la incipiente democracia de nuestro pa\u00eds, sin embargo, se ha convertido en un intento fallido y frustrado, producto de la mezquindad con la que act\u00faa la clase pol\u00edtica y la polarizaci\u00f3n y encono que imperan en la vida p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quienes defendemos la democracia como forma de gobierno, reconocemos que es un modelo perfectible y que depende de m\u00faltiples factores para su buen funcionamiento, particularmente de la voluntad y empe\u00f1o de los protagonistas pol\u00edticos y sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El discurso liberal democr\u00e1tico sostiene que la democracia es el peor sistema de gobierno existente, excepto todos los dem\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La democracia puede tener muchos defectos, pero comparada con otras formas de gobierno, resulta ser la menos perniciosa\u2026 al menos hasta ahora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El problema en M\u00e9xico es el uso que le hemos dado a la democracia, sus preceptos se distorsionan al someterla a los intereses de las minor\u00edas, cuando por definici\u00f3n, la democracia es exactamente lo contrario, es el poder de las mayor\u00edas, y eso termina incomodando aquellos que se dicen dem\u00f3cratas, pero que en realidad desprecian y temen al poder de las masas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace 2,400 a\u00f1os, Plat\u00f3n advert\u00eda que uno de los riesgos de la democracia, se encuentra en c\u00f3mo evitar que se convierta en un sistema de mercader\u00edas ret\u00f3ricas y de comercio de las opiniones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tanto Plat\u00f3n como Arist\u00f3teles vieron con acierto que un sistema en el que todos podemos ser elegidos, abre la posibilidad de que una persona que no es capaz de distinguir entre su opini\u00f3n personal (tanto en contenido como en grado de certeza), y la verdad (comprensi\u00f3n de las causas fundamentales de la realidad hist\u00f3rica), constitu\u00eda un verdadero peligro para la Rep\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La llegada y ascenso al poder de L\u00f3pez Obrador ha puesto en jaque a las elites en M\u00e9xico, su forma de gobernar, su discurso populista dirigido a las masas y su obsesi\u00f3n por construir un nuevo r\u00e9gimen que atenta contra los intereses de las \u00e9lites pol\u00edticas y econ\u00f3micas, han provocado un escenario de encono y polarizaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u00f3pez Obrador lleg\u00f3 al poder por la v\u00eda democr\u00e1tica, es decir, por la voluntad de las mayor\u00edas (30 millones de votantes), eso ha incomodado a las minor\u00edas, quienes no terminan de aceptar esta realidad. En respuesta, intentan dinamitar a este gobierno por todas las v\u00edas, hasta ahora sin \u00e9xito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El refer\u00e9ndum de revocaci\u00f3n de mandato era una gran oportunidad para mostrar en las urnas el repudio y rechazo hacia las pol\u00edticas de este gobierno, pero la oposici\u00f3n decidi\u00f3 no participar y opt\u00f3 por el boicot, llamando a no votar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La realidad es que la oposici\u00f3n no tiene la fuerza popular para enfrentar a AMLO, a pesar de los malos resultados de su gobierno, L\u00f3pez Obrador goza de una aceptaci\u00f3n y popularidad que sus adversarios no entienden ni aceptan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese escenario, quienes creemos en los valores y virtudes de la democracia, vemos con tristeza como un ejercicio que deber\u00eda abonar al fortalecimiento de la participaci\u00f3n ciudadana, ha sido viciado, distorsionado y boicoteado desde su origen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Unos y otros se han encargado de dinamitar el refer\u00e9ndum, los responsables de este desastre tienen nombre, por un lado los funcionarios p\u00fablicos y actores pol\u00edticos en el gobierno, quienes han violentado la ley de manera burda, c\u00ednica y descarada una y otra vez, por otro, una oposici\u00f3n torpe, sin autoridad moral y sometida a los intereses de la \u00e9lite, y que reh\u00fayen a las reglas de la democracia; y finalmente por un \u00e1rbitro (INE) que abiertamente ha tomado partido, abandonando la imparcialidad que su posici\u00f3n obliga.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En estas lamentables circunstancias, lo que debi\u00f3 ser un gran ejercicio democr\u00e1tico de participaci\u00f3n directa, termin\u00f3 siendo un bodrio de la pol\u00edtica mexicana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este domingo se efectuar\u00e1 el refer\u00e9ndum de revocaci\u00f3n de mandato, un ejercicio democr\u00e1tico de participaci\u00f3n directa in\u00e9dito en la historia moderna de M\u00e9xico. El refer\u00e9ndum deber\u00eda ser un avance en la construcci\u00f3n de la incipiente democracia de nuestro pa\u00eds, sin embargo, se ha convertido en un intento fallido y frustrado, producto de la mezquindad con [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":49166,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[429],"tags":[430],"class_list":["post-49165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artillero","tag-moises-hernandez-yoldi","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/49165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=49165"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/49165\/revisions"}],"predecessor-version":[{"id":49167,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/49165\/revisions\/49167"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/49166"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=49165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=49165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=49165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}