{"id":4321,"date":"2021-02-11T20:24:01","date_gmt":"2021-02-12T02:24:01","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=4321"},"modified":"2021-02-11T20:24:03","modified_gmt":"2021-02-12T02:24:03","slug":"asegura-el-gtav-que-vacuna-de-astrazeneca-es-segura-y-eficaz-para-adultos-mayores","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/02\/11\/asegura-el-gtav-que-vacuna-de-astrazeneca-es-segura-y-eficaz-para-adultos-mayores\/","title":{"rendered":"Asegura el GTAV que vacuna de AstraZeneca es segura y eficaz para adultos mayores"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La vacuna AstraZeneca contra el virus SARS-CoV-2 es segura y eficaz para personas adultas mayores, por lo que se puede aplicar a este sector de la poblaci\u00f3n en M\u00e9xico, confirm\u00f3 la coordinadora del Grupo T\u00e9cnico Asesor de Vacunas (GTAV) en M\u00e9xico, Celia Alpuche Aranda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La tambi\u00e9n directora del Centro de Investigaci\u00f3n sobre Enfermedades Infecciosas del Instituto Nacional de Salud P\u00fablica (INSP), dijo que luego de revisar los estudios e informes presentados por el Consejo de Vacunaci\u00f3n de la Uni\u00f3n Europea y la Organizaci\u00f3n Mundial de la Salud (OMS), sobre este biol\u00f3gico, el GTAV determin\u00f3 que la vacuna de AstraZeneca y la Universidad de Oxford no representa riesgo a la salud de las personas adultas mayores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El GTAV para la vacuna contra COVID-19 en M\u00e9xico emiti\u00f3 tres recomendaciones de car\u00e1cter intermedio para uso de emergencia de la vacuna AstraZeneca AZD1222.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la presentaci\u00f3n del informe sobre la evoluci\u00f3n de la pandemia, Alpuche Aranda dio a conocer los resultados del an\u00e1lisis realizado por este grupo aut\u00f3nomo integrado por especialistas nacionales e internacionales.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El GTAV determin\u00f3 recomendar el uso de la vacuna AstraZeneca AZD1222 en personas mayores de 18 a\u00f1os en adelante, aplicar la dosis en intervalos de 8 a 12 semanas, as\u00ed como su utilizaci\u00f3n cuando existan variantes del virus SARS-CoV-2.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El an\u00e1lisis se desarroll\u00f3 a partir los resultados de investigaciones realizadas por la Agencia Europea de Medicamentos; el Comit\u00e9 Mixto de Vacunaci\u00f3n e Inmunizaci\u00f3n del Reino Unido, y la Organizaci\u00f3n Mundial de la Salud.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, el subsecretario de Prevenci\u00f3n y Promoci\u00f3n de la Salud, Hugo L\u00f3pez-Gatell Ram\u00edrez, agradeci\u00f3 las recomendaciones y anticip\u00f3 que con el apoyo del Consejo Nacional de Ciencia y Tecnolog\u00eda (Conacyt), se integr\u00f3 un grupo cient\u00edfico en el que participan instituciones p\u00fablicas de investigaci\u00f3n en biolog\u00eda y biomedicina para expandir la capacidad de vigilancia de las variantes de cepas emergentes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que el pr\u00f3ximo domingo llega a nuestro pa\u00eds un embarque con 500 mil dosis de la vacuna de AstraZeneca, que es independiente de las que se envasar\u00e1n en nuestro pa\u00eds de fabricaci\u00f3n argentina.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que la empresa mexicana Laboratorios de Biol\u00f3gicos y Reactivos de M\u00e9xico (Birmex), S.A. de C.V., estableci\u00f3 un contrato con el Instituto Serol\u00f3gico de la India por poco m\u00e1s de dos millones de vacunas AstraZeneca. El embarque que llegar\u00e1 el 14 de febrero forma parte de ese paquete.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anunci\u00f3 que las vacunas de CanSino Biologics y de Sinovac, ambas de origen chino, recibieron hoy de Cofepris autorizaci\u00f3n para uso de emergencia. La primera llegar\u00e1 en granel para ser envasada en una planta de Quer\u00e9taro y la segunda arribar\u00e1 a M\u00e9xico envasada desde China.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En otro orden de ideas, dio a conocer que se han registrado cuatro millones 382 mil 593 personas adultas mayores en el portal&nbsp;<a href=\"file:\/\/\/C:\/Users\/RCortesA\/Downloads\/mivacuna.salud.%20gob.mx\">mivacuna.salud. gob.mx<\/a>, e invit\u00f3 a la poblaci\u00f3n mayor de 60 a\u00f1os a registrarse con el fin de ajustar acciones log\u00edsticas que garanticen el suministro de vacunas en todo el pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la conferencia de prensa, el director general de Epidemiolog\u00eda, Jos\u00e9 Luis Alom\u00eda Zegarra present\u00f3 el Comunicado T\u00e9cnico Diario (CTD) sobre la situaci\u00f3n de COVID-19 en M\u00e9xico, del cual resalt\u00f3 que se mantiene la tendencia en la reducci\u00f3n del n\u00famero de casos estimados con 31 por ciento, mientras que el porcentaje de casos activos se mantiene en tres por ciento y la ocupaci\u00f3n hospitalaria disminuy\u00f3 otro punto porcentual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, se registran m\u00e1s personas vacunadas con esquemas completos al llegar a 84 mil 592; que casos activos estimados, que asciende a 67 mil 536. Record\u00f3 que 80 por ciento de las personas que se contagian tienen s\u00edntomas leves y a la fecha un mill\u00f3n 519 mil se han recuperado de la enfermedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, se han aplicado 724 mil 797 vacunas contra COVID-19 y se tiene un avance de 14 por ciento en el n\u00famero del personal de salud con su esquema completo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vacuna AstraZeneca contra el virus SARS-CoV-2 es segura y eficaz para personas adultas mayores, por lo que se puede aplicar a este sector de la poblaci\u00f3n en M\u00e9xico, confirm\u00f3 la coordinadora del Grupo T\u00e9cnico Asesor de Vacunas (GTAV) en M\u00e9xico, Celia Alpuche Aranda. La tambi\u00e9n directora del Centro de Investigaci\u00f3n sobre Enfermedades Infecciosas del [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":4322,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[359,175,1287,162,661],"class_list":["post-4321","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-coronavirus","tag-covid-19","tag-grupo-tecnico-asesor-de-vacunas","tag-portada","tag-sars-cov-2","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/4321","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=4321"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/4321\/revisions"}],"predecessor-version":[{"id":4323,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/4321\/revisions\/4323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/4322"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=4321"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=4321"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=4321"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}