{"id":42759,"date":"2022-02-27T08:56:24","date_gmt":"2022-02-27T14:56:24","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=42759"},"modified":"2022-02-27T08:56:26","modified_gmt":"2022-02-27T14:56:26","slug":"ucrania-acepta-negociar-con-rusia","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/02\/27\/ucrania-acepta-negociar-con-rusia\/","title":{"rendered":"Ucrania acepta negociar con Rusia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Presidencia de Ucrania acept\u00f3 tener conversaciones con Rusia, las cuales se llevar\u00e1n a cabo en la frontera con Bielorrusia, cerca de la zona de exclusi\u00f3n de Ch\u00e9rnobil, una decisi\u00f3n tomada tras la mediaci\u00f3n del presidente bielorruso Alexander Lukashenko. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;La delegaci\u00f3n ucraniana se entrevistar\u00e1 con la (delegaci\u00f3n) rusa sin fijar condiciones previas en la frontera ucranio-bielorrusa, en la regi\u00f3n del r\u00edo Pr\u00edpiat&#8221;, declar\u00f3 la presidencia en un comunicado. <\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En la misma comunicaci\u00f3n, se subraya que el presidente bielorruso, Alexander Lukashenko &#8220;ha asumido la responsabilidad de garantizar que todos los aviones, helic\u00f3pteros y misiles estacionados en territorio bielorruso permanezcan en tierra durante el viaje, las conversaciones y el regreso de la delegaci\u00f3n ucraniana&#8221; a Kiev. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poco antes, Rusia inform\u00f3 de que su delegaci\u00f3n se dirig\u00eda a la regi\u00f3n de G\u00f3mel, cercana a la frontera ucraniana, para negociar un posible cese de las hostilidades con Ucrania, seg\u00fan el jefe de la delegaci\u00f3n rusa, Vladimir Medinski, asesor del presidente Vladimir Putin. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Toda nuestra delegaci\u00f3n ahora parte hacia la regi\u00f3n de G\u00f3mel&#8221;, afirm\u00f3 el negociador ruso, citado por la agencia TASS.<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p> &#8220;En estos momentos se est\u00e1 elaborando la ruta para elegir el lugar de la regi\u00f3n de G\u00f3mel donde se garantizar\u00e1 la m\u00e1xima seguridad para la parte ucraniana&#8221;, hab\u00eda dicho Medinski. <\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el vocero del Kremlin, Dmitri Peskov, afirm\u00f3 que los presidentes de Bielorrusia y Ucrania, Alexander Lukashenko y Volodimir Zelenski, hablaron por tel\u00e9fono y que tras ello, Lukashenko pidi\u00f3 a su colega ruso, Vladimir Putin, que no retirase a la delegaci\u00f3n rusa que esperaba en Minsk. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rusia estaba esperando la respuesta de Ucrania sobre la celebraci\u00f3n de negociaciones y hab\u00eda dado de plazo hasta las 15:00 horas.\u00a0 <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/internacional\/ucrania-acepta-negociar-con-rusia-entre-su-frontera-y-bielorrusia\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Presidencia de Ucrania acept\u00f3 tener conversaciones con Rusia, las cuales se llevar\u00e1n a cabo en la frontera con Bielorrusia, cerca de la zona de exclusi\u00f3n de Ch\u00e9rnobil, una decisi\u00f3n tomada tras la mediaci\u00f3n del presidente bielorruso Alexander Lukashenko. &#8220;La delegaci\u00f3n ucraniana se entrevistar\u00e1 con la (delegaci\u00f3n) rusa sin fijar condiciones previas en la frontera [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":42761,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[181],"tags":[162,537,5041],"class_list":["post-42759","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-portada","tag-rusia","tag-ucrania","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/42759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=42759"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/42759\/revisions"}],"predecessor-version":[{"id":42760,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/42759\/revisions\/42760"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/42761"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=42759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=42759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=42759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}