{"id":40655,"date":"2022-02-13T09:55:40","date_gmt":"2022-02-13T15:55:40","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=40655"},"modified":"2022-02-13T10:00:53","modified_gmt":"2022-02-13T16:00:53","slug":"emite-mexico-alerta-para-no-visitar-ucrania","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/02\/13\/emite-mexico-alerta-para-no-visitar-ucrania\/","title":{"rendered":"Emite M\u00e9xico alerta para no visitar Ucrania"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ante la crisis que atraviesa Ucrania, la Secretar\u00eda de Relaciones Exteriores (SRE) emiti\u00f3 una alerta a todos los turistas mexicanos de no viajar a ese pa\u00eds, alertando sobre los riesgos que se corren en esta regi\u00f3n. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cA la luz de la reducci\u00f3n de la conectividad a\u00e9rea en Ucrania, se invita a las personas mexicanas que visiten Ucrania por turismo o negocios a evitar viajar a ese pa\u00eds en este momento, ante el creciente riesgo de quedar varados\u201d, public\u00f3 la canciller\u00eda mexicana en una alerta de viaje. <\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, para los mexicanos que radican en este pa\u00eds, la SRE sugiri\u00f3 a la comunidad mexicana a tomar las rutas comerciales a\u00fan disponibles si su deseo es abandonar Ucrania.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante las \u00faltimas horas, la aerol\u00ednea KLM suspendi\u00f3 sus vuelos con destino a Ucrania &#8220;hasta nuevo aviso&#8221;, esto tras los temores de una invasi\u00f3n por parte de Rusia a este pa\u00eds del este europeo. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;El pr\u00f3ximo vuelo hacia la capital Kiev est\u00e1 programado para esta noche, pero no se efectuar\u00e1&#8221;, precis\u00f3 KLM, agregando que esa decisi\u00f3n se tom\u00f3 despu\u00e9s de realizar un an\u00e1lisis sobre la seguridad aeroportuaria y una posible \u201calerta roja\u201d para los enlaces a\u00e9reos. <\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">La canciller\u00eda mexicana recomend\u00f3 a todos los turistas y ciudadanos mexicanos que viven en aquella naci\u00f3n mantenerse informados sobre el estatus de operaciones de las l\u00edneas a\u00e9reas que dan servicio a Ucrania. <\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cSe sugiere seguir oportunamente las instrucciones de las autoridades ucranianas. Lleva siempre una copia de tu pasaporte mexicano y una identificaci\u00f3n oficial con fotograf\u00eda, conserva una copia electr\u00f3nica de los mismos\u201d, a\u00f1adi\u00f3 la dependencia.\u200b<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/mexico-emite-alerta-para-no-visitar-ucrania\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ante la crisis que atraviesa Ucrania, la Secretar\u00eda de Relaciones Exteriores (SRE) emiti\u00f3 una alerta a todos los turistas mexicanos de no viajar a ese pa\u00eds, alertando sobre los riesgos que se corren en esta regi\u00f3n. \u201cA la luz de la reducci\u00f3n de la conectividad a\u00e9rea en Ucrania, se invita a las personas mexicanas que [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":40656,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[162,5041],"class_list":["post-40655","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-portada","tag-ucrania","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/40655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=40655"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/40655\/revisions"}],"predecessor-version":[{"id":40659,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/40655\/revisions\/40659"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/40656"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=40655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=40655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=40655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}