{"id":36558,"date":"2022-01-15T11:20:53","date_gmt":"2022-01-15T17:20:53","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=36558"},"modified":"2022-01-15T11:20:54","modified_gmt":"2022-01-15T17:20:54","slug":"representa-putin-una-profunda-amenaza-a-la-paz-en-europa","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2022\/01\/15\/representa-putin-una-profunda-amenaza-a-la-paz-en-europa\/","title":{"rendered":"Representa Putin una profunda amenaza a la paz en Europa"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Europa tiene una larga y sangrienta historia de guerras, de fronteras brutalmente disputadas y naciones e imperios que labraron destructivos surcos lejos de casa. Pero una triste cosecha de dolor y p\u00e9rdida despu\u00e9s de la Segunda Guerra Mundial fue seguida por d\u00e9cadas de relativa paz y prosperidad, incluso durante una Guerra Fr\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hoy esa paz&nbsp;est\u00e1 siendo severamente puesta a prueba&nbsp;por el presidente de Rusia, Vladimir Putin, mientras concentra tropas en la frontera de Ucrania y los diplom\u00e1ticos est\u00e1n levantando la alarma en t\u00e9rminos inequ\u00edvocos. El embajador de Estados Unidos en la 57 naci\u00f3n, Organizaci\u00f3n para la Seguridad y la Cooperaci\u00f3n en Europa (OSCE), Michael Carpenter, advirti\u00f3 este jueves que la seguridad europea se enfrenta a una &#8220;crisis&#8221;, &#8220;el tambor de la guerra suena fuerte&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Putin, cuya naci\u00f3n enterr\u00f3 a decenas de millones de personas en las guerras europeas, est\u00e1 desenterrando nuevas quejas sobre la paz posterior a la Guerra Mundial, espec\u00edficamente el papel de la OTAN, la alianza defensiva transatl\u00e1ntica y el contrapunto al predecesor de Rusia, la Uni\u00f3n Sovi\u00e9tica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El verano pasado, en un documento de 20 p\u00e1ginas que citaba siglos de historia salpicada de sangre, Putin reclam\u00f3 Ucrania, que en 1991 recuper\u00f3 su independencia tras el colapso de la Uni\u00f3n Sovi\u00e9tica, afirmando que &#8220;los rusos, ucranianos y bielorrusos son todos descendientes de la antigua Rus, que era el estado m\u00e1s grande de Europa&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concluy\u00f3 que &#8220;nuestros lazos espirituales, humanos y de civilizaci\u00f3n formados durante siglos tienen su origen en las mismas fuentes&#8230; la verdadera soberan\u00eda de Ucrania solo es posible en asociaci\u00f3n con Rusia&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Como comandante del quinto ej\u00e9rcito m\u00e1s grande del mundo, y apenas a la mitad de un gobierno esperado de casi cuatro d\u00e9cadas, Putin est\u00e1 preparando el escenario para reclamar su derecho al igual que lo hicieron sus antepasados,&nbsp;colocando fuerzas en la frontera de Ucrania&nbsp;a la espera de su mando.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de haber invadido Crimea en 2014, los temores de que las tropas rusas vuelvan a cruzar la frontera nunca han sido tan altos<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La \u00faltima semana de conversaciones \u2014bilateralmente con EE.UU. en Ginebra el lunes, con la OTAN en Bruselas el mi\u00e9rcoles y que culmin\u00f3 en la OSCE en Viena el jueves\u2014 que pretend\u00edan aliviar las tensiones, parece haber logrado lo contrario y atrincher\u00f3 a los emisarios de Putin en una ret\u00f3rica hostil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viceministro de Relaciones Exteriores de Rusia, Sergey Ryabkov, marc\u00f3 la pauta el lunes exigiendo &#8220;garant\u00edas f\u00e9rreas, a prueba de agua, a prueba de balas, legalmente vinculantes, no promesas, no salvaguardias, garant\u00edas&#8221; de que la OTAN niegue a Ucrania y la membres\u00eda y retroceda a las l\u00edneas de 1997.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dos d\u00edas despu\u00e9s, tras las conversaciones de la OTAN en Bruselas, otro ministro de Asuntos Exteriores, el diputado Alexander Grushko, amenaz\u00f3 con la fuerza si no consiguen lo que quieren. &#8220;Tenemos un conjunto de medidas t\u00e9cnico-militares legales que aplicaremos si sentimos una amenaza real a [nuestra] seguridad, y ya la sentimos\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este jueves, cuando las conversaciones llegaron a la OSCE, cuyo territorio circunnavega el hemisferio norte desde la tundra helada m\u00e1s oriental de Rusia hasta el extremo occidental helado de Alaska y donde tanto Rusia como Ucrania son miembros, se hab\u00eda formado un permafrost diplom\u00e1tico. El embajador de Rusia en la OSCE, Alexander Lukashevich, advirti\u00f3 sobre &#8220;un momento de la verdad&#8221; con &#8220;consecuencias catastr\u00f3ficas&#8221; si se violan los &#8220;principios&#8221; de Rusia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este viernes en Mosc\u00fa, el ministro de Relaciones Exteriores de Putin, Sergei Lavrov, advirti\u00f3 que &#8220;Occidente se dej\u00f3 llevar&#8221;, y recurriendo a la ley popular rusa, insinu\u00f3 que la diplomacia de Putin puede haber seguido su curso, diciendo: &#8220;Hemos estado sacando provecho lentamente, pero ahora es el momento de nosotros para remontar&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: CNN<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Europa tiene una larga y sangrienta historia de guerras, de fronteras brutalmente disputadas y naciones e imperios que labraron destructivos surcos lejos de casa. Pero una triste cosecha de dolor y p\u00e9rdida despu\u00e9s de la Segunda Guerra Mundial fue seguida por d\u00e9cadas de relativa paz y prosperidad, incluso durante una Guerra Fr\u00eda. Hoy esa paz&nbsp;est\u00e1 [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":16172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[181],"tags":[512,2838,8622,8621,8623],"class_list":["post-36558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-amenaza","tag-europa","tag-profunda","tag-putin","tag-representa","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/36558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=36558"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/36558\/revisions"}],"predecessor-version":[{"id":36559,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/36558\/revisions\/36559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/16172"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=36558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=36558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=36558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}