{"id":33543,"date":"2021-12-11T09:24:35","date_gmt":"2021-12-11T15:24:35","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=33543"},"modified":"2021-12-11T09:24:36","modified_gmt":"2021-12-11T15:24:36","slug":"formaliza-amlo-nombramiento-de-victoria-rodriguez-al-frente-de-banxico","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/12\/11\/formaliza-amlo-nombramiento-de-victoria-rodriguez-al-frente-de-banxico\/","title":{"rendered":"Formaliza AMLO nombramiento de Victoria Rodr\u00edguez al frente de Banxico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El presidente Andr\u00e9s Manuel L\u00f3pez Obrador formaliz\u00f3 este viernes el nombramiento de\u00a0Victoria Rodr\u00edguez Ceja\u00a0como gobernadora del Banco de M\u00e9xico (Banxico).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La a\u00fan subsecretaria de Egresos se convertir\u00e1 as\u00ed en&nbsp;<strong>la primera mujer en dirigir el Banco Central.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Consejer\u00eda Jur\u00eddica del Ejecutivo Federal env\u00edo un oficio al secretario de la Junta de Gobierno mediante el que formaliz\u00f3 la designaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLe informo que con fundamento en los art\u00edculos 38, 40 y 41 de la Ley del Banco de M\u00e9xico, el Titular del Poder Ejecutivo Federal, nombr\u00f3 a dicha persona (Victoria Rodr\u00edguez Ceja) Gobernadora del Banco de M\u00e9xico, a partir del 1 de enero de 2022 y hasta el 31 de diciembre de 2027\u2033, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Senado aval\u00f3 el nombramiento de la funcionaria de Hacienda como integrante de la Junta de Gobierno del Banxico a inicios de este mes. Sustituir\u00e1 a Alejandro D\u00edaz de Le\u00f3n en el cargo de gobernador de la instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: El Economista<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El presidente Andr\u00e9s Manuel L\u00f3pez Obrador formaliz\u00f3 este viernes el nombramiento de\u00a0Victoria Rodr\u00edguez Ceja\u00a0como gobernadora del Banco de M\u00e9xico (Banxico). La a\u00fan subsecretaria de Egresos se convertir\u00e1 as\u00ed en&nbsp;la primera mujer en dirigir el Banco Central. La Consejer\u00eda Jur\u00eddica del Ejecutivo Federal env\u00edo un oficio al secretario de la Junta de Gobierno mediante el que [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":33545,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[2988,162,7412],"class_list":["post-33543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-banxico","tag-portada","tag-victoria-rodriguez-ceja","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/33543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33543"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/33543\/revisions"}],"predecessor-version":[{"id":33544,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/33543\/revisions\/33544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/33545"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}