{"id":33446,"date":"2021-12-10T09:18:28","date_gmt":"2021-12-10T15:18:28","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=33446"},"modified":"2021-12-10T09:19:04","modified_gmt":"2021-12-10T15:19:04","slug":"mueren-mas-de-50-migrantes-en-accidente-de-trailer","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/12\/10\/mueren-mas-de-50-migrantes-en-accidente-de-trailer\/","title":{"rendered":"Mueren m\u00e1s de 50 migrantes en accidente de tr\u00e1iler"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">M\u00e1s de 50 migrantes, principalmente guatemaltecos, murieron ayer en un accidente luego de que un conductor manej\u00f3 a exceso de velocidad el tr\u00e1iler en el que viajaban hacinados y perdi\u00f3\u00a0el control al salir de una curva en la carretera Chiapa de Corzo-Tuxtla Guti\u00e9rrez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos de los centroamericanos murieron sofocados mientras se intentaba rescatarlos de entre los restos de la caja; al cierre de la edici\u00f3n el gobernador de Chiapas, Rutilio Escand\u00f3n, inform\u00f3 que sumaban 54 muertos y 105 heridos (83 hombres y 22 mujeres), tres de\u00a0gravedad. La\u00a0Fiscal\u00eda General de la Rep\u00fablica (FGR) anunci\u00f3 que atraer\u00e1 la investigaci\u00f3n del accidente.\u00a0<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cPor ser un lamentable caso de migrantes acaecido en una v\u00eda de comunicaci\u00f3n federal, la fiscal\u00eda especializada en materia de derechos humanos\u00a0actuar\u00e1 junto con la fiscal\u00eda especializada de control regional, as\u00ed como con todo el personal t\u00e9cnico y de apoyo que sea necesario, para llevar a cabo las diligencias correspondientes\u201d. <\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio P\u00fablico de la Federaci\u00f3n asever\u00f3 que mantiene coordinaci\u00f3n permanente con las autoridades de Chiapas y con la Guardia Nacional, \u201cen un equipo integral de trabajo, que ya se encuentra en funciones\u201d. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El tr\u00e1iler Kenworth, con placas 444-DW-4, volc\u00f3 alrededor de\u00a0las 15:30 horas y justo despu\u00e9s de pasar un ret\u00e9n.\u00a0Primero se impact\u00f3 en un muro de contenci\u00f3n y\u00a0enseguida con un puente peatonal. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La caja se desprendi\u00f3, gir\u00f3 sobre la carretera y decenas de migrantes salieron disparados. Los cuerpos quedaron esparcidos en distintos puntos del asfalto. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan la fiscal\u00eda estatal, algunos murieron sofocados y otros aplastados por la caja del tr\u00e1iler.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin dar m\u00e1s detalles, la Direcci\u00f3n General de Protecci\u00f3n Civil asever\u00f3 que en el accidente ocurrido a la altura del puente Belisario Dom\u00ednguez y Ribera Cauhar\u00e9 estuvo involucrado otro cami\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/chiapa-corzo-100-kilometros-hora-54-migrantes-muertos\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 50 migrantes, principalmente guatemaltecos, murieron ayer en un accidente luego de que un conductor manej\u00f3 a exceso de velocidad el tr\u00e1iler en el que viajaban hacinados y perdi\u00f3\u00a0el control al salir de una curva en la carretera Chiapa de Corzo-Tuxtla Guti\u00e9rrez. Algunos de los centroamericanos murieron sofocados mientras se intentaba rescatarlos de entre [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":33448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[1550,452,162],"class_list":["post-33446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-accidente","tag-migrantes","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/33446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=33446"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/33446\/revisions"}],"predecessor-version":[{"id":33447,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/33446\/revisions\/33447"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/33448"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=33446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=33446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=33446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}