{"id":31624,"date":"2021-11-22T10:20:33","date_gmt":"2021-11-22T16:20:33","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=31624"},"modified":"2021-11-22T10:20:34","modified_gmt":"2021-11-22T16:20:34","slug":"asesores-de-partidos-ganan-el-doble-que-consejeros-electorales","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/11\/22\/asesores-de-partidos-ganan-el-doble-que-consejeros-electorales\/","title":{"rendered":"Asesores de partidos ganan el doble que consejeros electorales"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Este a\u00f1o, los siete partidos pol\u00edticos nacionales cargaron al presupuesto del Instituto Nacional Electoral <strong>m\u00e1s de 66 millones de pesos en sueldos para 68 asesores y secretarios que les asisten y orientan dentro del Consejo General del INE<\/strong>, lo que la autoridad electoral debi\u00f3 pagar de manera adicional a los m\u00e1s de siete mil millones de pesos que repartieron en prerrogativas. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por decenas de personas que asesoran, orientan, explican, preparan los discursos y acompa\u00f1an a los representantes de partidos pol\u00edticos, ya sean los enviados directamente de los comit\u00e9s ejecutivos nacionales o de las bancadas del legislativo, al cierre del 2021, el INE pagar\u00e1 66 millones 289 mil 764 pesos s\u00f3lo en sus sueldos, lo que implica pr\u00e1cticamente el doble de los 34 millones de pesos que cobran anualmente en conjunto, los 11 integrantes del Consejo General. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con el directorio p\u00fablico del INE, el PRD es el que cuenta con m\u00e1s plazas con cargo al presupuesto del instituto, ya sean fijas o por honorarios, con 13 personas. Sin embargo, aunque le siguen el PAN y el Partido Verde Ecologista de M\u00e9xico, con 10 personas, estos dos equipos son los m\u00e1s costosos; despu\u00e9s est\u00e1n Morena, el PRI y el PT con nueve personas y Movimiento Ciudadano con ocho. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El viernes 19 de noviembre, el representante suplente de Morena, Euripides Flores, provoc\u00f3 que por primera vez en su historia, el INE decretara un receso por falta de orden, al intentar a gritos, imponer su posicionamiento fuera del orden del d\u00eda con el que exhibi\u00f3 que la autoridad electoral solicit\u00f3 presupuesto global por 21.6 millones de pesos para diez asesores de los consejeros. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El consejero presidente Lorenzo C\u00f3rdova le pidi\u00f3 decir a la ciudadan\u00eda cu\u00e1nto debe pagar el INE para los asesores de Morena que lo asisten a \u00e9l y al resto de los representantes de ese partido, lo que el morenista no supo responder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: <a href=\"https:\/\/www.milenio.com\/politica\/ine-asesores-partidos-ganan-doble-consejeros-electorales\">Milenio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este a\u00f1o, los siete partidos pol\u00edticos nacionales cargaron al presupuesto del Instituto Nacional Electoral m\u00e1s de 66 millones de pesos en sueldos para 68 asesores y secretarios que les asisten y orientan dentro del Consejo General del INE, lo que la autoridad electoral debi\u00f3 pagar de manera adicional a los m\u00e1s de siete mil millones [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[158],"tags":[5364,443,1623],"class_list":["post-31624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-consejeros","tag-ine","tag-partidos","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/31624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=31624"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/31624\/revisions"}],"predecessor-version":[{"id":31626,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/31624\/revisions\/31626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/598"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=31624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=31624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=31624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}