{"id":30858,"date":"2021-11-15T11:33:01","date_gmt":"2021-11-15T17:33:01","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=30858"},"modified":"2021-11-15T11:33:01","modified_gmt":"2021-11-15T17:33:01","slug":"el-chantaje-de-lorenzo-cordova-sin-dinero-no-hay-democracia","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/11\/15\/el-chantaje-de-lorenzo-cordova-sin-dinero-no-hay-democracia\/","title":{"rendered":"El chantaje de Lorenzo C\u00f3rdova: sin dinero, no hay democracia"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por: Mois\u00e9s Hern\u00e1ndez Yoldi<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Defender la autonom\u00eda e independencia del INE, no significa avalar los onerosos gastos y el excesivo aparato burocr\u00e1tico que sostiene esa instituci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El INE es -sin duda- un logro de la sociedad, una instituci\u00f3n que nos ha permitido garantizar y transparentar las elecciones en M\u00e9xico, elecciones que en el pasado eran una simulaci\u00f3n y que permitieron que el r\u00e9gimen pri\u00edsta se mantuviera por m\u00e1s de 70 a\u00f1os en el poder.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Antecedentes<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El origen del Instituto Nacional Electoral (INE) es el antiguo Instituto Federal Electoral (IFE), ese instituto inici\u00f3 actividades en 1990, con la primera sesi\u00f3n de su m\u00e1ximo \u00f3rgano de direcci\u00f3n:&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Consejo General, y su primer presidente fue Fernando Guti\u00e9rrez Barrios, quien fung\u00eda como titular de la Secretar\u00eda de Gobernaci\u00f3n. En ese entonces, el IFE era un organismo dependiente directamente del gobierno,&nbsp;y&nbsp;por ende, sometido a su voluntad e intereses.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El IFE sustituy\u00f3 a la Comisi\u00f3n Federal Electoral. Naci\u00f3 como resultado del escandaloso fraude de 1988, que llev\u00f3 a Carlos Salinas al poder, y que le rob\u00f3 la presidencia a Cuauht\u00e9moc C\u00e1rdenas, esto provoc\u00f3 una serie de reformas a la Constituci\u00f3n Pol\u00edtica, aprobadas el 4 de abril de 1990.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En 1994 se llev\u00f3 a cabo un proceso de ciudadanizaci\u00f3n de los&nbsp;Consejeros, que formaban parte del m\u00e1ximo \u00f3rgano de direcci\u00f3n, lo que tuvo como consecuencia el cambio de nombre del cargo de&nbsp;Consejero&nbsp;Magistrado por el de&nbsp;Consejero&nbsp;Ciudadano.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese momento la instituci\u00f3n alcanz\u00f3 su independencia respecto al Poder Ejecutivo, sin embargo, no contaba con los instrumentos para el arbitraje electoral, y se limitaba a procedimientos administrativos sancionadores dirigidos a los partidos pol\u00edticos.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bajo ese argumento, en el 2007 se le otorgaron facultades e instrumentos para sancionar no solo a los partidos pol\u00edticos, sino tambi\u00e9n a los ciudadanos, militantes y candidatos de los partidos pol\u00edticos, as\u00ed como a concesionarios y permisionarios de los medios electr\u00f3nicos de comunicaci\u00f3n (radio y televisi\u00f3n).&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fue as\u00ed como una instituci\u00f3n que naci\u00f3 con el mejor de los prop\u00f3sitos, fue adquiriendo atribuciones excesivas, y hoy se ha convertido en un \u00f3rgano sancionador y censurador con facultades punitivas.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Es momento de replantear las atribuciones y facultades del INE.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorenzo C\u00f3rdova y el resto de los consejeros, deben entender que no es posible mantener los excesos a los que se hab\u00edan acostumbrado, deben tambi\u00e9n ajustarse a una pol\u00edtica de austeridad, y lo primero que tendr\u00edan que hacer es un ajuste a sus ingresos, que comparados con sus hom\u00f3logos de otros pa\u00edses, resultan escandalosos y agraviantes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El chantaje: si no hay dinero, no hay democracia&nbsp;<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El pasado domingo por la madrugada, y luego de un marat\u00f3nico debate de m\u00e1s de 50 horas, los diputados aprobaron (con 273 votos a favor y 214 en contra) el Presupuesto de Egresos para 2022.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El presupuesto contempla un recorte de 5 mil millones de pesos para el INE, que ahora tendr\u00e1 19 mil 736 millones de pesos para ejercer en 2022, dinero que seg\u00fan Lorenzo C\u00f3rdova y Ciro Murayama, es insuficiente para cumplir con sus tareas.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo con la p\u00e1gina de transparencia del INE, C\u00f3rdova, al igual que los dem\u00e1s miembros del Consejo General, tiene una percepci\u00f3n bruta de 234 mil 519 pesos, de los cuales se deducen 65 mil 394 pesos, dejando un total neto de 169 mil 125 pesos.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, cuenta con un veh\u00edculo pagado por el instituto, una bonificaci\u00f3n de hasta 4 mil pesos para cubrir los costos de telefon\u00eda m\u00f3vil personal y hasta 14 mil pesos para gastos de alimentaci\u00f3n.&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los mexicanos estamos llamados a defender la democracia y a las instituciones que la garantizan, pero no a costa de excesos ni de una burocracia burguesa&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Mois\u00e9s Hern\u00e1ndez Yoldi Defender la autonom\u00eda e independencia del INE, no significa avalar los onerosos gastos y el excesivo aparato burocr\u00e1tico que sostiene esa instituci\u00f3n. El INE es -sin duda- un logro de la sociedad, una instituci\u00f3n que nos ha permitido garantizar y transparentar las elecciones en M\u00e9xico, elecciones que en el pasado eran [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":1333,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[429],"tags":[430],"class_list":["post-30858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artillero","tag-moises-hernandez-yoldi","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/30858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=30858"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/30858\/revisions"}],"predecessor-version":[{"id":30859,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/30858\/revisions\/30859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/1333"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=30858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=30858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=30858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}