{"id":30392,"date":"2021-11-11T10:08:14","date_gmt":"2021-11-11T16:08:14","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=30392"},"modified":"2021-11-11T10:08:15","modified_gmt":"2021-11-11T16:08:15","slug":"empresarios-llaman-a-mexicanos-a-consumir-productos-locales-durante-el-buen-fin","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/11\/11\/empresarios-llaman-a-mexicanos-a-consumir-productos-locales-durante-el-buen-fin\/","title":{"rendered":"Empresarios llaman a mexicanos a consumir productos locales durante el Buen Fin\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla | NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz. \u2013 Empresarios regionales del pa\u00eds llamaron a la ciudadan\u00eda a consumir durante el Buen Fin productos hechos en M\u00e9xico, pero de manera preferente productos locales hechos en cada estado y regi\u00f3n del pa\u00eds, como una manera de apoyar a la recuperaci\u00f3n laboral, econ\u00f3mica y productiva en cada localidad.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cLas cifras nos muestran que el consumo de bienes de origen importado se ha recuperado ya a niveles previos a la pandemia, pero en el caso del consumo de bienes y servicios de origen nacional a\u00fan falta y esto es porque muchas de las pymes regionales quebraron o tuvieron que disminuir actividades\u201d, se\u00f1al\u00f3 Jos\u00e9 Manuel Urreta Ortega, presidente de la Asociaci\u00f3n Nacional de Consejos Empresariales Regionales.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan datos reportados el d\u00eda de ayer por INEGI, en el acumulado enero \u2013 agosto de 2021 los bienes importados duraderos y semiduraderos crecieron 27.9%, mientras que los nacionales lo hicieron en tan s\u00f3lo 6.6%.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cLos indicadores del consumo privado en el mercado interior alertan sobre la urgente necesidad de ver al desarrollo regional del pa\u00eds como la mejor manera de integrar y sostener la recuperaci\u00f3n de la econom\u00eda y productividad mexicanas\u201d, se\u00f1al\u00f3 el presidente de ANCER.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello, tambi\u00e9n llamaron al Gobierno Federal a impulsar pol\u00edticas campa\u00f1as de impulso al consumo local, que se reflejen en un mayor flujo de recursos entre los mexicanos; esto es ya que, alert\u00f3, hoy en d\u00eda existen pocos programas econ\u00f3micos y productivos transversales o con el enfoque de desarrollo regional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">V\u00edctor del Rio R de la Gala, presidente del Consejo Coordinador Empresarial de Campeche, indic\u00f3 que todos los mexicanos debemos tomar conciencia y apoyar a nuestro mercado interno a trav\u00e9s del consumo de productos y servicios generados localmente, y con ello fortalecer a las empresas legalmente establecidas de cada comunidad y fomentar la econom\u00eda y generaci\u00f3n de empleos en todo el territorio nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los empresarios regionales se\u00f1alaron que el consumo local podr\u00eda seguir recuper\u00e1ndose en la recta final del a\u00f1o en esta temporada que genera mayores ventas, pero s\u00f3lo si los mexicanos cobramos conciencia de la importancia de impulsar el emprendedurismo de j\u00f3venes, las redes regionales de producci\u00f3n y comercio y a todas las peque\u00f1as empresas y negocios en el pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla | NV Noticias Veracruz. \u2013 Empresarios regionales del pa\u00eds llamaron a la ciudadan\u00eda a consumir durante el Buen Fin productos hechos en M\u00e9xico, pero de manera preferente productos locales hechos en cada estado y regi\u00f3n del pa\u00eds, como una manera de apoyar a la recuperaci\u00f3n laboral, econ\u00f3mica y productiva en cada localidad. \u201cLas [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":30393,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[6261,301,257],"class_list":["post-30392","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-buen-fin","tag-empresarios","tag-mexicanos","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/30392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=30392"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/30392\/revisions"}],"predecessor-version":[{"id":30394,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/30392\/revisions\/30394"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/30393"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=30392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=30392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=30392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}