{"id":29641,"date":"2021-11-03T11:37:29","date_gmt":"2021-11-03T17:37:29","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=29641"},"modified":"2021-11-03T11:37:30","modified_gmt":"2021-11-03T17:37:30","slug":"acusan-que-el-snte-retraso-dos-anos-la-renovacion-sindical","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/11\/03\/acusan-que-el-snte-retraso-dos-anos-la-renovacion-sindical\/","title":{"rendered":"Acusan que el SNTE retras\u00f3 dos a\u00f1os la renovaci\u00f3n sindical"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas&nbsp;Utrilla&nbsp;| NV Noticias<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veracruz. \u2013&nbsp;Integrantes de la Dirigencia Colegiada Nacional de la Asociaci\u00f3n Civil 32 por la Reivindicaci\u00f3n Magisterial, exhortaron a los maestros a presionar desde los estados para que se publique la convocatoria que permita renovar dicho comit\u00e9.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rafael Ochoa Guzm\u00e1n, integrante de la dirigencia, acus\u00f3 que la directiva nacional del Sindicato Nacional de Trabajadores de la Educaci\u00f3n lleva 2 a\u00f1os evadiendo la renovaci\u00f3n.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por ello acus\u00f3 que el SNTE no garantiza democracia sindical.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u00a0\u201cDebieron haber emitido la convocatoria ya para este relevo hace 2 a\u00f1os y no lo hacen, por tramposos&#8221;.\u00a0<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que se concret\u00f3 una reforma laboral que obliga a una renovaci\u00f3n aplicando el voto universal directo y secreto, por ello pidi\u00f3 que no se retrase m\u00e1s la convocatoria.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Reiter\u00f3 el llamado a los maestros de cada una de las entidades federativas para que se concrete la renovaci\u00f3n sindical.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u201cLa convocatoria no ha salido porque\u00a0son una bola de tramposos, entre unos y otros se tapan y el gobierno no les aprieta como debiera hacer\u201d.\u00a0<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Dijo que existe hartazgo entre los trabajadores de la educaci\u00f3n, por lo que no descart\u00f3 que puedan llevar a cabo movilizaciones.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que seguir\u00e1n recorriendo el pa\u00eds para presionar a que se garantice la democracia del sindicato de maestros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas&nbsp;Utrilla&nbsp;| NV Noticias&nbsp; Veracruz. \u2013&nbsp;Integrantes de la Dirigencia Colegiada Nacional de la Asociaci\u00f3n Civil 32 por la Reivindicaci\u00f3n Magisterial, exhortaron a los maestros a presionar desde los estados para que se publique la convocatoria que permita renovar dicho comit\u00e9.&nbsp; Rafael Ochoa Guzm\u00e1n, integrante de la dirigencia, acus\u00f3 que la directiva nacional del Sindicato Nacional de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":29643,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[154],"tags":[2411,1668],"class_list":["post-29641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-sindicato","tag-snte","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/29641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=29641"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/29641\/revisions"}],"predecessor-version":[{"id":29644,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/29641\/revisions\/29644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/29643"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=29641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=29641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=29641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}