{"id":29498,"date":"2021-11-01T16:16:38","date_gmt":"2021-11-01T22:16:38","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=29498"},"modified":"2021-11-01T16:16:38","modified_gmt":"2021-11-01T22:16:38","slug":"monitoreara-uv-porcentaje-estudiantes-vacunados","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/11\/01\/monitoreara-uv-porcentaje-estudiantes-vacunados\/","title":{"rendered":"Monitorear\u00e1 UV porcentaje de estudiantes vacunados para retorno seguro"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Gabriela Rasgado | NV Noticias<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Xalapa. &#8211; El rector de la Universidad Veracruzana (UV) Mart\u00edn Aguilar S\u00e1nchez, adelant\u00f3 que se realizar\u00e1 una nueva encuesta entre alumnos de la m\u00e1xima casa de estudios para saber c\u00f3mo avanz\u00f3 el porcentaje de vacunaci\u00f3n entre estos, en el marco del regreso a clases presenciales.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al respecto, sostuvo\u00a0que\u00a0si bien se ha permitido un regreso voluntario principalmente de los estudiantes de las generaciones 2020 y 2021 al ser los que no conoc\u00edan la universidad, no se tiene una cifra de cu\u00e1ntos volvieron a las aulas, aunque entre ambas generaciones son m\u00e1s de 31 mil.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin&nbsp;embargo, sentenci\u00f3 que los alumnos que volvieron, sea la cantidad que sea, deben&nbsp;observar las reglas de sanidad que deben prevalecer entre ellos, pues en lo que se respecta a las instalaciones, asegur\u00f3 que se realizaron acciones para asegurar el respeto a dichas medidas.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Por eso estamos llamando al autocuidado&#8221;, sostuvo al se\u00f1alar que en tanto los j\u00f3venes acatan las disposiciones, se tendr\u00e1 mayor certeza al saber qu\u00e9 cantidad de estudiantes ya fueron vacunados.\u00a0<\/p><\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Lo que nos da m\u00e1s un porcentaje de tranquilidad, es el proceso de la vacunaci\u00f3n. Solicit\u00e9 un nuevo sondeo o encuesta para saber c\u00f3mo se increment\u00f3 el porcentaje\u00a0de estudiantes vacunados, cu\u00e1l fue el porcentaje que lleg\u00f3 y c\u00f3mo est\u00e1n viendo los estudiantes el regreso&#8221;, sostuvo.\u00a0<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El rector reconoci\u00f3 que el regreso a clases ha sido complicado porque se debe estar monitoreando frecuentemente a los estudiantes, qu\u00e9 est\u00e1 pasando con ellos y c\u00f3mo sienten la vuelta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sostuvo que en funci\u00f3n de los resultados que arroje dicha encuesta, se ir\u00e1 ideando el regreso completo que al momento se contempla hasta el pr\u00f3ximo a\u00f1o para todos los estudiantes.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que tambi\u00e9n se monitorean las nuevas variantes que han ido surgiendo a lo largo de la pandemia para que sea un factor a tener en cuenta dicha programaci\u00f3n del retorno.&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;La tenemos que afinar de acuerdo al resultado de este proceso; yo quisiera que el pr\u00f3ximo semestre todas las entidades volvieran, por eso es importante c\u00f3mo terminamos el proceso de vacunaci\u00f3n, cu\u00e1les son los niveles de los contagios y c\u00f3mo se van incrementando&#8221;, acot\u00f3.\u00a0<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Gabriela Rasgado | NV Noticias&nbsp; Xalapa. &#8211; El rector de la Universidad Veracruzana (UV) Mart\u00edn Aguilar S\u00e1nchez, adelant\u00f3 que se realizar\u00e1 una nueva encuesta entre alumnos de la m\u00e1xima casa de estudios para saber c\u00f3mo avanz\u00f3 el porcentaje de vacunaci\u00f3n entre estos, en el marco del regreso a clases presenciales.\u00a0 Al respecto, sostuvo\u00a0que\u00a0si bien se [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":26223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[156],"tags":[277,1164,2903],"class_list":["post-29498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-estudiantes","tag-uv","tag-vacunados","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/29498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=29498"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/29498\/revisions"}],"predecessor-version":[{"id":29499,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/29498\/revisions\/29499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/26223"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=29498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=29498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=29498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}