{"id":2801,"date":"2021-01-28T18:29:48","date_gmt":"2021-01-29T00:29:48","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=2801"},"modified":"2021-01-28T18:29:50","modified_gmt":"2021-01-29T00:29:50","slug":"gobierno-federal-cerro-apoyos-para-productores-del-campo","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/01\/28\/gobierno-federal-cerro-apoyos-para-productores-del-campo\/","title":{"rendered":"Gobierno Federal cerr\u00f3 apoyos para productores del campo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Julio Escobar \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Coatzacoalcos. &#8211; El presidente del Comit\u00e9 Regional Campesino de la Confederaci\u00f3n Nacional Campesina (CNC) en la regi\u00f3n sur, Joaqu\u00edn Montillo G\u00f3mez, denunci\u00f3 que el Gobierno Federal cerr\u00f3 los apoyos para los productores del campo.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;No hay apoyo para el campo, no hay apoyo para producci\u00f3n alimenticia, e incluso es mentira que digan que el nuevo Gobierno ha venido a cambiar la pol\u00edtica agropecuaria, es mentira, hay menos inversi\u00f3n en el campo pero el campesino es noble y est\u00e1 produciendo mucho m\u00e1s&#8221;, sostuvo.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que a pesar de las trabas del Gobierno Federal, en el mercado las frutas y verduras est\u00e1n a bajo costo y hay m\u00e1s producci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Montillo G\u00f3mez destac\u00f3 que para este 2021 los campesinos no esperan un crecimiento en el campo, sin embargo, insisti\u00f3 en que seguir\u00e1n en la siembra de los productos agr\u00edcolas.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>&#8220;Tenemos compa\u00f1eros que est\u00e1n sembrando hect\u00e1reas de sand\u00eda, hect\u00e1reas de naranja, de pepino, y bueno que la gente coma, que se alimente, aunque se venda barato, la cuesti\u00f3n aqu\u00ed es que se siga trabajando&#8221;, reiter\u00f3.<\/p><\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">El l\u00edder campesino asever\u00f3 que crisis en el campo veracruzano, recrudeci\u00f3 con la falta de empleos, inseguridad y la crisis sanitaria por el COVID-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la regi\u00f3n hay por lo menos 5 mil productores de ma\u00edz, uno de los sectores m\u00e1s importantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Julio Escobar \/ NV Noticias Coatzacoalcos. &#8211; El presidente del Comit\u00e9 Regional Campesino de la Confederaci\u00f3n Nacional Campesina (CNC) en la regi\u00f3n sur, Joaqu\u00edn Montillo G\u00f3mez, denunci\u00f3 que el Gobierno Federal cerr\u00f3 los apoyos para los productores del campo. &#8220;No hay apoyo para el campo, no hay apoyo para producci\u00f3n alimenticia, e incluso es mentira [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":2802,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[156],"tags":[839,219,180],"class_list":["post-2801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-campo","tag-cnc","tag-veracruz","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/2801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=2801"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/2801\/revisions"}],"predecessor-version":[{"id":2803,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/2801\/revisions\/2803"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/2802"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=2801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=2801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=2801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}