{"id":27850,"date":"2021-10-17T13:55:58","date_gmt":"2021-10-17T18:55:58","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=27850"},"modified":"2021-10-17T14:00:01","modified_gmt":"2021-10-17T19:00:01","slug":"la-intolerancia-y-la-cerrazon","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2021\/10\/17\/la-intolerancia-y-la-cerrazon\/","title":{"rendered":"La intolerancia y la cerraz\u00f3n"},"content":{"rendered":"\n<p class=\"has-text-align-right wp-block-paragraph\"><strong>Por: Mois\u00e9s Hern\u00e1ndez Yoldi<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La ma\u00f1ana de este s\u00e1bado asist\u00ed al evento organizado y convocado por Coparmex Veracruz, donde la senadora Lilly T\u00e9llez ofreci\u00f3 una conferencia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La trayectoria de T\u00e9llez como periodista es ampliamente conocida, la hoy senadora por el PAN, fue una de las reporteras y conductoras estelares de TV Azteca.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sus logros profesionales la llevaron a convertirse en una figura p\u00fablica, y en el 2018, a invitaci\u00f3n de Andr\u00e9s Manuel L\u00f3pez Obrador, acept\u00f3 la candidatura por Morena para buscar un esca\u00f1o en el senado de la Rep\u00fablica, resultando ganadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 14 de abril del 2020, Lilly T\u00e9llez anunci\u00f3 que abandonaba la bancada de Morena en el Senado, a trav\u00e9s de un tuit donde escribi\u00f3:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDejo la bancada de Morena por diferencias de criterio. Agradezco a Alfonso Durazo, a Ricardo Monreal y en especial al Presidente de la rep\u00fablica por el respeto que han tenido hacia mi persona. Me quedo como senadora sin partido, comprometida a seguir hablando con la verdad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Despu\u00e9s de este anuncio, las diferencias entre T\u00e9llez y Morena, se hicieron m\u00e1s grandes, hasta llegar a una ruptura total.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El 3 de junio del 2020, dos meses despu\u00e9s de renunciar a Morena, Marko Cort\u00e9s y Mauricio Kuri, dirigente nacional del PAN y coordinador de la bancada panista en el senado respectivamente, anunciaron que T\u00e9llez se un\u00eda a las filas de Partido Acci\u00f3n Nacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de ese momento, Lilly T\u00e9llez se convirti\u00f3 en una de las m\u00e1s f\u00e9rreas cr\u00edticas de la llamada 4T. Sus discursos en el senado han impactado en un sector de la sociedad, que ve en ella a una mujer con el valor y la capacidad para cuestionar, criticar y se\u00f1alar los errores del actual gobierno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lilly T\u00e9llez es -sin duda- un activo pol\u00edtico importante para la oposici\u00f3n, y su presencia en reuniones como las de esta ma\u00f1ana, sirven para despertar conciencias y mover voluntades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, preocupa la cerraz\u00f3n que existe en la oposici\u00f3n, la falta de apertura para escuchar la cr\u00edtica, la postura soberbia y arrogante que no les permite escuchar a quienes de buena voluntad y con el \u00e1nimo de contribuir, se\u00f1alan que la estrategia y las acciones no est\u00e1n dando resultados, al menos no los que se esperan desde la sociedad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo ocurrido esta ma\u00f1ana durante el evento, fue una muestra de ello, cuando el periodista y acad\u00e9mico Eduardo Manzanares, hizo una cr\u00edtica puntual y respetuosa a la estrategia de la oposici\u00f3n, se\u00f1alando que han ca\u00eddo en el \u201cjuego\u201d del presidente, y que es este quien les marca agenda a trav\u00e9s de sus distractores y de su famosa conferencia ma\u00f1anera.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manzanares cit\u00f3 una frase que la propia T\u00e9llez us\u00f3 en el senado para referirse a la Guardia Nacional, cuando dijo que eran \u201cel grupo de edecanes m\u00e1s caros de M\u00e9xico\u201d (22 de septiembre del 2021), Manzanares acomod\u00f3 la frase para referirse a la oposici\u00f3n, lo que provoc\u00f3 una reacci\u00f3n visceral y fuera de lugar de la senadora, quien se mostr\u00f3 pasional y poco reflexiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNo te permito que me digas \u201cedec\u00e1n\u201d, yo he demostrado tener el valor y la autoridad para criticar al presidente\u2026\u201d dijo T\u00e9llez en un tono col\u00e9rico y soberbio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cr\u00edtica y comentario de Manzanares, era en contra de la oposici\u00f3n en general, no en contra de la senadora T\u00e9llez, a los que todos los que nos encontr\u00e1bamos en el sal\u00f3n, le reconocemos su valor, por eso est\u00e1bamos ah\u00ed, para escucharla; lamentablemente su reacci\u00f3n visceral y su falta de tolerancia, result\u00f3 muy desafortunada, y revela la cerraz\u00f3n con la que se est\u00e1 actuando en la oposici\u00f3n, donde no hay espacio para la autocr\u00edtica y todo aquello que resulte contrario a su agenda, es descalificado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mal y de malas andamos en M\u00e9xico, donde la sociedad pensante tiene que lidiar con un r\u00e9gimen cada vez m\u00e1s autoritario y una oposici\u00f3n ensimismada, incapaz de escuchar y entender las causas y las razones del porqu\u00e9 llegamos hasta aqu\u00ed.<\/p>\n\n\n\n<p class=\"has-small-font-size wp-block-paragraph\"><em>Mois\u00e9s Hern\u00e1ndez Yoldi estudi\u00f3 Ciencias de la Comunicaci\u00f3n y periodismo en la Universidad Veracruzana, con diplomado en Marketing Digital por la Universidad de San Diego y 30 a\u00f1os de experiencia en Medios electr\u00f3nicos y digitales.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por: Mois\u00e9s Hern\u00e1ndez Yoldi La ma\u00f1ana de este s\u00e1bado asist\u00ed al evento organizado y convocado por Coparmex Veracruz, donde la senadora Lilly T\u00e9llez ofreci\u00f3 una conferencia. La trayectoria de T\u00e9llez como periodista es ampliamente conocida, la hoy senadora por el PAN, fue una de las reporteras y conductoras estelares de TV Azteca. Sus logros profesionales [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":27852,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[429],"tags":[430],"class_list":["post-27850","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artillero","tag-moises-hernandez-yoldi","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/27850","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=27850"}],"version-history":[{"count":2,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/27850\/revisions"}],"predecessor-version":[{"id":27881,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/27850\/revisions\/27881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/27852"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=27850"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=27850"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=27850"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}