{"id":222801,"date":"2026-07-17T09:54:29","date_gmt":"2026-07-17T15:54:29","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=222801"},"modified":"2026-07-17T09:54:39","modified_gmt":"2026-07-17T15:54:39","slug":"designara-la-onu-nuevos-expertos-para-revisar-la-indagatoria-de-los-43-sheinbaum","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2026\/07\/17\/designara-la-onu-nuevos-expertos-para-revisar-la-indagatoria-de-los-43-sheinbaum\/","title":{"rendered":"Designar\u00e1 la ONU nuevos expertos para revisar la indagatoria de los 43: Sheinbaum"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El objetivo en el caso Ayotzinapa es conocer la verdad, que haya justicia y saber d\u00f3nde est\u00e1n los 43 j\u00f3venes desaparecidos, ratific\u00f3 la presidenta Claudia Sheinbaum Pardo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que ser\u00e1 la oficina en M\u00e9xico del Alto Comisionado de Naciones Unidas para los Derechos Humanos la que proponga a los expertos independientes que revisar\u00e1n el giro en la investigaci\u00f3n, pero no ser\u00e1n \u2013dijo\u2013 ex integrantes del Grupo Interdisciplinario de Expertos Independientes (GIEI).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la ma\u00f1anera, a la pregunta sobre la posibilidad de que pudiera hablar \u00c1ngela Buitrago, ex integrante del grupo, afirm\u00f3 que \u00e9ste \u201cya no existe, y no es lo mismo que sean parte de la asesor\u00eda en una instituci\u00f3n independiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cNosotros pedimos a la oficina del Alto Comisionado para los Derechos Humanos que viera la posibilidad de incorporar a estos expertos o a otros. La respuesta fue que no ser\u00edan ellos y propondr\u00e1n a otros\u201d. El tema \u201cincluso lo habl\u00e9 con el titular de ese organismo de la ONU (Volker T\u00fcrk) cuando estuvo en M\u00e9xico\u201d, record\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se\u00f1al\u00f3 que el fiscal del caso, Mauricio Pazar\u00e1n, ha aportado una visi\u00f3n distinta al expediente que \u201cest\u00e1 dando muchos resultados\u201d, al recuperar la investigaci\u00f3n cient\u00edfica y encontrar \u201calgunas omisiones en las pesquisas que se hicieron\u201d, de lo cual se hablar\u00e1 una vez que acuerde con los padres de los 43 normalistas, con quienes se re\u00fane cada dos o tres meses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn algunas cosas estamos de acuerdo en c\u00f3mo se est\u00e1 llevando la investigaci\u00f3n, en otras seguimos platicando, porque no se puede hablar de desacuerdo, y por respeto a ellos, hasta que no tengamos su evaluaci\u00f3n podremos salir p\u00fablicamente con lo que hemos encontrado; no podr\u00edamos hablar de este tema antes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Manifest\u00f3 que la revisi\u00f3n de las pesquisas no podr\u00eda hacerla directamente el gobierno, \u201cni las organizaciones de derechos humanos, que (con) muchas de ellas ha habido desencuentros por las opiniones e investigaciones que se han venido haciendo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mandataria se\u00f1al\u00f3 que se podr\u00eda hablar con Buitrago, \u201cpero s\u00ed hay diferencias en varios temas que tienen que ver incluso con la resoluci\u00f3n de un juez en Tamaulipas, que liber\u00f3 a presuntos culpables de la desaparici\u00f3n de los j\u00f3venes, algunos de ellos que hab\u00edan sido torturados y otros no, donde esta comisi\u00f3n estuvo de acuerdo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: La <a href=\"https:\/\/www.jornada.com.mx\/noticia\/2026\/07\/17\/politica\/designara-la-onu-nuevos-expertos-para-revisar-la-indagatoria-de-los-43-sheinbaum\">Jornada<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>El objetivo en el caso Ayotzinapa es conocer la verdad, que haya justicia y saber d\u00f3nde est\u00e1n los 43 j\u00f3venes desaparecidos, ratific\u00f3 la presidenta Claudia Sheinbaum Pardo. Indic\u00f3 que ser\u00e1 la oficina en M\u00e9xico del Alto Comisionado de Naciones Unidas para los Derechos Humanos la que proponga a los expertos independientes que revisar\u00e1n el giro [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":222803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[158],"tags":[25639,2801,513,162],"class_list":["post-222801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-caso-ayotzinapa","tag-claudia-sheinbaum","tag-onu","tag-portada","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/222801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=222801"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/222801\/revisions"}],"predecessor-version":[{"id":222806,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/222801\/revisions\/222806"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/222803"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=222801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=222801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=222801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}