{"id":222538,"date":"2026-07-14T13:59:09","date_gmt":"2026-07-14T19:59:09","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=222538"},"modified":"2026-07-14T13:59:18","modified_gmt":"2026-07-14T19:59:18","slug":"audios-atribuidos-a-gobernadora-de-bc-no-revelan-entrega-de-informacion-sheinbaum","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2026\/07\/14\/audios-atribuidos-a-gobernadora-de-bc-no-revelan-entrega-de-informacion-sheinbaum\/","title":{"rendered":"Audios atribuidos a gobernadora de BC no revelan entrega de informaci\u00f3n: Sheinbaum"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La presidenta Claudia Sheinbaum Pardo y el secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, afirmaron este martes que los audios atribuidos a la gobernadora de Baja California, Marina del Pilar \u00c1vila Olmeda, no revelan la entrega de informaci\u00f3n confidencial ni contienen elementos que justifiquen, por ahora, el inicio de una investigaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuestionado sobre la posibilidad de que la Fiscal\u00eda General de la Rep\u00fablica o el gobierno federal abran una indagatoria, Garc\u00eda Harfuch sostuvo en la conferencia matutina en Palacio Nacional que en las grabaciones &#8220;no se infiere que se vaya a dar informaci\u00f3n confidencial&#8221; y explic\u00f3 que en las mesas estatales de seguridad participan autoridades de distintos \u00f3rdenes de gobierno y se revisa principalmente la incidencia delictiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;No hay una informaci\u00f3n como tal que tenga un grado de sensibilidad que nos preocupe que fuera compartido con alguna autoridad, si es que fuera el caso (&#8230;), porque todav\u00eda no se sabe exactamente qu\u00e9 autoridad era con la persona que estaba hablando&#8221;, se\u00f1al\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario a\u00f1adi\u00f3 que ya convers\u00f3 con la mandataria estatal, quien le dio la misma explicaci\u00f3n que posteriormente hizo p\u00fablica mediante un comunicado. Agreg\u00f3 que una investigaci\u00f3n s\u00f3lo proceder\u00eda si existieran indicios de un delito. &#8220;Se abrir\u00eda una investigaci\u00f3n si hubiera un delito, pero en el audio, sinceramente, no se infiere ning\u00fan tipo de delito&#8221;, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, Sheinbaum record\u00f3 que la gobernadora ya ofreci\u00f3 una explicaci\u00f3n sobre los hechos y enfatiz\u00f3 que ni siquiera est\u00e1 claro con qui\u00e9n sostuvo la conversaci\u00f3n telef\u00f3nica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;No sabemos ni siquiera si es de autoridades estadunidenses o no. Y ella da una explicaci\u00f3n posterior de que es parte de una comunicaci\u00f3n y que no pone en riesgo absolutamente nada de la seguridad de Baja California&#8221;, afirm\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La mandataria tambi\u00e9n rechaz\u00f3 que el caso pueda equipararse con la investigaci\u00f3n abierta en Chihuahua por la presunta participaci\u00f3n de agentes de la CIA en operativos dentro del estado. Explic\u00f3 que en aquel asunto &#8220;est\u00e1 demostrado que hab\u00eda gente de una agencia operando en territorio. Eso es una violaci\u00f3n flagrante a la Ley de Seguridad Nacional&#8221;, mientras que en este caso \u00fanicamente existe una llamada telef\u00f3nica cuya contraparte no ha sido identificada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Si hay que investigar, que se investigue, pero son dos cosas completamente distintas&#8221;, sostuvo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sheinbaum tambi\u00e9n cuestion\u00f3 el origen de la filtraci\u00f3n de los audios. &#8220;No s\u00e9 c\u00f3mo llegan estas llamadas de tel\u00e9fono. Qui\u00e9n quiere filtrar esta informaci\u00f3n. Vale la pena preguntarlo como periodistas&#8221;, coment\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: La <a href=\"https:\/\/www.jornada.com.mx\/noticia\/2026\/07\/14\/politica\/audios-atribuidos-a-gobernadora-de-bc-no-revelan-entrega-de-informacion-confidencial-que-deba-ser-investigada-sheinbaum\">Jornada<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La presidenta Claudia Sheinbaum Pardo y el secretario de Seguridad y Protecci\u00f3n Ciudadana, Omar Garc\u00eda Harfuch, afirmaron este martes que los audios atribuidos a la gobernadora de Baja California, Marina del Pilar \u00c1vila Olmeda, no revelan la entrega de informaci\u00f3n confidencial ni contienen elementos que justifiquen, por ahora, el inicio de una investigaci\u00f3n. Cuestionado sobre [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":222540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[158],"tags":[4487,2801],"class_list":["post-222538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-baja-california","tag-claudia-sheinbaum","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/222538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=222538"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/222538\/revisions"}],"predecessor-version":[{"id":222544,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/222538\/revisions\/222544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/222540"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=222538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=222538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=222538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}