{"id":220899,"date":"2026-06-29T13:47:41","date_gmt":"2026-06-29T19:47:41","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=220899"},"modified":"2026-06-29T13:47:50","modified_gmt":"2026-06-29T19:47:50","slug":"francia-y-oman-acuerdan-colaborar-en-el-desminado-del-estrecho-de-ormuz","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2026\/06\/29\/francia-y-oman-acuerdan-colaborar-en-el-desminado-del-estrecho-de-ormuz\/","title":{"rendered":"Francia y Om\u00e1n acuerdan colaborar en el desminado del estrecho de Ormuz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Francia y Om\u00e1n firmaron un acuerdo de cooperaci\u00f3n para el desminado del estrecho de Ormuz, con el objetivo de garantizar la seguridad del tr\u00e1fico mar\u00edtimo, anunci\u00f3 el presidente franc\u00e9s, Emmanuel Macron.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este lunes, Macron recibi\u00f3 en Par\u00eds al sult\u00e1n oman\u00ed, Haitham bin Tariq\u200b\u200b\u200b. Durante la reuni\u00f3n, ambas partes sellaron una serie de acuerdos en los \u00e1mbitos econ\u00f3mico, cient\u00edfico, cultural e industrial.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Trabajamos juntos para la desescalada en Oriente Medio. Decidimos colaborar, en coordinaci\u00f3n con nuestros socios, en el desminado del estrecho para asegurar las rutas mar\u00edtimas y garantizar un paso libre y sin condiciones a trav\u00e9s del estrecho de Ormuz&#8221;, escribi\u00f3 Macron en la red social X.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la noche del 17 al 18 de junio, los presidentes de Estados Unidos e Ir\u00e1n suscribieron por separado un memorando de entendimiento que puso fin a m\u00e1s de tres meses de hostilidades entre sus pa\u00edses y abri\u00f3 la v\u00eda para negociar un acuerdo definitivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Fuente: La <a href=\"https:\/\/www.jornada.com.mx\/noticia\/2026\/06\/29\/mundo\/francia-y-oman-acuerdan-colaborar-en-el-desminado-del-estrecho-de-ormuz\">Jornada<\/a> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Francia y Om\u00e1n firmaron un acuerdo de cooperaci\u00f3n para el desminado del estrecho de Ormuz, con el objetivo de garantizar la seguridad del tr\u00e1fico mar\u00edtimo, anunci\u00f3 el presidente franc\u00e9s, Emmanuel Macron.&nbsp; Este lunes, Macron recibi\u00f3 en Par\u00eds al sult\u00e1n oman\u00ed, Haitham bin Tariq\u200b\u200b\u200b. Durante la reuni\u00f3n, ambas partes sellaron una serie de acuerdos en los [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":220901,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[181],"tags":[33093,1056,33537],"class_list":["post-220899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-estrecho-de-ormuz","tag-francia","tag-oman","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/220899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=220899"}],"version-history":[{"count":3,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/220899\/revisions"}],"predecessor-version":[{"id":220903,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/220899\/revisions\/220903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/220901"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=220899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=220899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=220899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}