{"id":210372,"date":"2026-02-26T12:38:17","date_gmt":"2026-02-26T18:38:17","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=210372"},"modified":"2026-02-26T12:38:22","modified_gmt":"2026-02-26T18:38:22","slug":"urgen-a-reducir-requisitos-para-apertura-de-gasolineras","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2026\/02\/26\/urgen-a-reducir-requisitos-para-apertura-de-gasolineras\/","title":{"rendered":"Urgen a reducir requisitos para apertura de gasolineras"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Jes\u00fas Utrilla \/ NV Noticias <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La apertura y operaci\u00f3n de gasolineras en el pa\u00eds enfrenta una carga regulatoria que supera los 100 requisitos anuales por estaci\u00f3n, lo que complica la inversi\u00f3n y retrasa nuevos proyectos, se\u00f1al\u00f3 el sector empresarial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ricardo Quiroz, presidente de la Asociaci\u00f3n Mexicana de Proveedores de Estaciones de Servicio (AMPES), advirti\u00f3 que lejos de simplificarse, los tr\u00e1mites se han incrementado y, en muchos casos, se duplican entre autoridades municipales, estatales y federales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAl d\u00eda de hoy, nosotros como proveedores sabemos que una estaci\u00f3n debe cumplir m\u00e1s de 100 requisitos al a\u00f1o, y cada d\u00eda, lejos de reducir, est\u00e1n aumentando m\u00e1s. Hay requisitos que se duplican; lo tiene el municipio, tambi\u00e9n el estado, luego la CEA y luego la CNE, y se tiene que trabajar con el gobierno para que un solo documento sea v\u00e1lido para varias \u00e1reas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Explic\u00f3 que algunas dependencias federales ya han emitido acuerdos de simplificaci\u00f3n administrativa, como la Comisi\u00f3n Nacional de Energ\u00eda (CNE) y la Agencia de Seguridad, Energ\u00eda y Ambiente (ASEA), lo que representa un avance; sin embargo, consider\u00f3 que a\u00fan es necesario armonizar criterios entre instituciones para evitar cargas innecesarias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Detall\u00f3 que adem\u00e1s de los lineamientos en materia energ\u00e9tica y ambiental, las estaciones de servicio deben cumplir con disposiciones del Instituto Mexicano del Seguro Social, la Secretar\u00eda del Trabajo y Previsi\u00f3n Social y otras instancias, lo que impacta directamente en la estructura de costos, sobre todo ante cambios como el aumento al salario m\u00ednimo y la reducci\u00f3n de la jornada laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quiroz enfatiz\u00f3 que la simplificaci\u00f3n de tr\u00e1mites no necesariamente requiere nuevas leyes, sino coordinaci\u00f3n entre dependencias federales encabezadas por la Secretar\u00eda de Energ\u00eda y la Secretar\u00eda de Medio Ambiente y Recursos Naturales, con el fin de homologar criterios y facilitar la apertura de nuevas estaciones sin comprometer la seguridad ni el cumplimiento normativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jes\u00fas Utrilla \/ NV Noticias La apertura y operaci\u00f3n de gasolineras en el pa\u00eds enfrenta una carga regulatoria que supera los 100 requisitos anuales por estaci\u00f3n, lo que complica la inversi\u00f3n y retrasa nuevos proyectos, se\u00f1al\u00f3 el sector empresarial. Ricardo Quiroz, presidente de la Asociaci\u00f3n Mexicana de Proveedores de Estaciones de Servicio (AMPES), advirti\u00f3 que [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":117570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[154],"tags":[3557,4766],"class_list":["post-210372","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-veracruz","tag-apertura","tag-gasolineras","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/210372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=210372"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/210372\/revisions"}],"predecessor-version":[{"id":210373,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/210372\/revisions\/210373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/117570"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=210372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=210372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=210372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}