{"id":208521,"date":"2026-02-06T13:44:06","date_gmt":"2026-02-06T19:44:06","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=208521"},"modified":"2026-02-06T13:44:10","modified_gmt":"2026-02-06T19:44:10","slug":"piden-denunciar-a-empresas-que-evaden-pagar-salario-minimo-en-veracruz","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2026\/02\/06\/piden-denunciar-a-empresas-que-evaden-pagar-salario-minimo-en-veracruz\/","title":{"rendered":"Piden denunciar a empresas que evaden pagar salario m\u00ednimo  en Veracruz"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Sam Ojeda \/ NV Noticias<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Xalapa.- A pesar de los incrementos al salario m\u00ednimo, en Veracruz persisten empresas que simulan cumplir la ley, pero no pagan ni el ingreso base legal ni prestaciones como aguinaldo y vacaciones, denunci\u00f3 el diputado local del PT, Adri\u00e1n Gonz\u00e1lez Naveda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El legislador se\u00f1al\u00f3 que han recibido quejas de trabajadores en municipios como Xalapa, Coatepec y la zona del Valle de Perote, aunque advirti\u00f3 que la pr\u00e1ctica se replica en distintas regiones del estado. Indic\u00f3 que uno de los esquemas m\u00e1s usados es el pago a destajo, es decir, por pieza producida, lo que puede encubrir el incumplimiento de derechos laborales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl salario m\u00ednimo es obligatorio por ley, no es una concesi\u00f3n, no es un capricho, es una obligaci\u00f3n legal que tiene el patr\u00f3n con el trabajador\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Record\u00f3 que el salario m\u00ednimo vigente es de 315 pesos diarios y que su aumento en los \u00faltimos a\u00f1os ha sido significativo, por lo que consider\u00f3 grave que a\u00fan existan centros de trabajo que no lo respeten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn territorio nos encontramos con muchas quejas de trabajadores que argumentan que no se les paga el salario m\u00ednimo (\u2026) no podemos permitir la simulaci\u00f3n, la ilegalidad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00f1adi\u00f3 que el salario base y las prestaciones establecidas en la Ley Federal del Trabajo no pueden sustituirse con esquemas que reduzcan el ingreso real de las personas trabajadoras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstas prestaciones son obligatorias (\u2026) aguinaldo y vacaciones\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gonz\u00e1lez Naveda llam\u00f3 a la poblaci\u00f3n trabajadora a denunciar ante las autoridades laborales y tambi\u00e9n ante representantes populares, y adelant\u00f3 que promover\u00e1n inspecciones federales para detectar a los patrones que incurren en estas pr\u00e1cticas.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sam Ojeda \/ NV Noticias Xalapa.- A pesar de los incrementos al salario m\u00ednimo, en Veracruz persisten empresas que simulan cumplir la ley, pero no pagan ni el ingreso base legal ni prestaciones como aguinaldo y vacaciones, denunci\u00f3 el diputado local del PT, Adri\u00e1n Gonz\u00e1lez Naveda. El legislador se\u00f1al\u00f3 que han recibido quejas de trabajadores [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":84383,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[156],"tags":[496,6423,1161],"class_list":["post-208521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-empresas","tag-pago","tag-salario-minimo","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/208521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=208521"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/208521\/revisions"}],"predecessor-version":[{"id":208523,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/208521\/revisions\/208523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/84383"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=208521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=208521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=208521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}