{"id":190222,"date":"2025-08-11T15:07:02","date_gmt":"2025-08-11T21:07:02","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=190222"},"modified":"2025-08-11T15:07:06","modified_gmt":"2025-08-11T21:07:06","slug":"restaura-ayuntamiento-mural-de-xallitic","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/08\/11\/restaura-ayuntamiento-mural-de-xallitic\/","title":{"rendered":"Restaura Ayuntamiento mural de Xallitic"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">*Trabajos se concluir\u00e1n en septiembre<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Xalapa, Ver.- Con el fin de recuperar el espacio p\u00fablico, fortalecer la identidad y celebrar el segundo aniversario de Xallitic como Barrio M\u00e1gico, el Ayuntamiento lleva a cabo los trabajos de restauraci\u00f3n del mural \u201cEl paso de Hern\u00e1n Cort\u00e9s por Xalapa\u201d, ubicado en la calle Dr. Rafael Lucio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Departamento de Imagen Urbana de la Direcci\u00f3n de Obras P\u00fablicas solicit\u00f3 que se realizaran los trabajos, mismos que iniciaron la semana pasada bajo el cuidado de la restauradora y egresada de la Escuela Nacional de Conservaci\u00f3n, Restauraci\u00f3n y Museograf\u00eda \u201cManuel del Castillo Negrete\u201d, Ver\u00f3nica Fern\u00e1ndez de Castro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La especialista en pintura mural ya realiz\u00f3 la restauraci\u00f3n de esta misma obra hace 15 a\u00f1os y, ahora, nuevamente est\u00e1 a cargo de las labores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La restauradora explic\u00f3 que el pr\u00f3ximo mes se concluir\u00edan los trabajos que incluyen el resanado con arena fina y acabados acordes con la textura original del mural, para conservar la homogeneidad de la t\u00e9cnica y la pintura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ver\u00f3nica Fern\u00e1ndez de Castro cuenta con 30 a\u00f1os de experiencia y ha trabajado en la restauraci\u00f3n de diversos murales ubicados en escuelas y edificios p\u00fablicos de ciudades como Tuxpan, Papantla, Poza Rica, San Andr\u00e9s Tuxtla, Santiago Tuxtla, y el Paseo de los Lagos, en Xalapa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mural \u201cEl paso de Hern\u00e1n Cort\u00e9s por Xalapa\u201d es una obra del artista Francisco Salmer\u00f3n Tinarejo, realizada en la d\u00e9cada de 1960, bajo la t\u00e9cnica de acr\u00edlico sobre aplanado de cal y arena.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El trabajo describe la Ruta de Hern\u00e1n Cort\u00e9s en su viaje de la Villa Rica de la Vera Cruz a M\u00e9xico, y su paso por Xalapa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mural en que destacan los cuatro barrios que dieron origen a Xalapa, es considerado patrimonio art\u00edstico del siglo XX.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>*Trabajos se concluir\u00e1n en septiembre Xalapa, Ver.- Con el fin de recuperar el espacio p\u00fablico, fortalecer la identidad y celebrar el segundo aniversario de Xallitic como Barrio M\u00e1gico, el Ayuntamiento lleva a cabo los trabajos de restauraci\u00f3n del mural \u201cEl paso de Hern\u00e1n Cort\u00e9s por Xalapa\u201d, ubicado en la calle Dr. Rafael Lucio. El Departamento [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":190223,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[156],"tags":[32180],"class_list":["post-190222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estado","tag-mural-xallitic","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/190222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=190222"}],"version-history":[{"count":1,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/190222\/revisions"}],"predecessor-version":[{"id":190224,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/190222\/revisions\/190224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/190223"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=190222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=190222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=190222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}