{"id":188351,"date":"2025-07-12T17:22:44","date_gmt":"2025-07-12T23:22:44","guid":{"rendered":"https:\/\/nvnoticias.mx\/?p=188351"},"modified":"2025-07-12T17:22:46","modified_gmt":"2025-07-12T23:22:46","slug":"buscan-a-exsecretario-de-seguridad-de-adan-augusto-por-presuntos-nexos-con-la-delincuencia-organizada","status":"publish","type":"post","link":"https:\/\/nvnoticias.mx\/index.php\/2025\/07\/12\/buscan-a-exsecretario-de-seguridad-de-adan-augusto-por-presuntos-nexos-con-la-delincuencia-organizada\/","title":{"rendered":"Buscan a exsecretario de Seguridad de Ad\u00e1n Augusto por presuntos nexos con la delincuencia organizada"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hern\u00e1n Berm\u00fadez Requena, exsecretario de Seguridad y Protecci\u00f3n Ciudadana durante el gobierno de Ad\u00e1n Augusto L\u00f3pez y despu\u00e9s en el de Carlos Manuel Merino Campos, gobernador de Tabasco, es pr\u00f3fugo internacional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo anterior lo confirm\u00f3 el comandante de la 30 Zona Militar, general Miguel \u00c1ngel L\u00f3pez Mart\u00ednez, en entrevista para Radio F\u00f3rmula, dijo que desde el 14 de febrero de este a\u00f1o hay una orden de aprehensi\u00f3n contra el exfuncionario estatal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El actual gobernador de Tabasco, Javier May Rodr\u00edguez, dijo que Berm\u00fadez Requena era quien presuntamente comandaba un grupo de la delincuencia organizada que opera en ese estado y que habr\u00eda permitido que en administraciones pasadas c\u00e9lulas criminales \u201cecharan ra\u00edces\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo que detalla el comandante en entrevista es que el mismo d\u00eda en que un juez orden\u00f3 su captura, el exfuncionario sali\u00f3 del pa\u00eds desde M\u00e9rida, Yucat\u00e1n, rumbo a Panam\u00e1, hizo escala en Espa\u00f1a y actualmente se le rastrea en Brasilia, capital de Brasil.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEl 14 de febrero, sali\u00f3 la orden de aprehensi\u00f3n contra Requena, ese d\u00eda hay registros que abandon\u00f3 el pa\u00eds de M\u00e9rida hacia Panam\u00e1\u201d, dijo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Agreg\u00f3 que otras cinco personas ligadas con estos grupos delincuenciales tambi\u00e9n cuentan con una orden de aprehensi\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hern\u00e1n Berm\u00fadez Requena, exsecretario de Seguridad y Protecci\u00f3n Ciudadana durante el gobierno de Ad\u00e1n Augusto L\u00f3pez y despu\u00e9s en el de Carlos Manuel Merino Campos, gobernador de Tabasco, es pr\u00f3fugo internacional. Lo anterior lo confirm\u00f3 el comandante de la 30 Zona Militar, general Miguel \u00c1ngel L\u00f3pez Mart\u00ednez, en entrevista para Radio F\u00f3rmula, dijo que desde [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":188354,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[157],"tags":[16465,20642],"class_list":["post-188351","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nacional","tag-adan-augusto-lopez","tag-exsecretario","wp-image-borders"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/188351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/comments?post=188351"}],"version-history":[{"count":2,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/188351\/revisions"}],"predecessor-version":[{"id":188353,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/posts\/188351\/revisions\/188353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media\/188354"}],"wp:attachment":[{"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/media?parent=188351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/categories?post=188351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nvnoticias.mx\/index.php\/wp-json\/wp\/v2\/tags?post=188351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}